{"id":4033,"count":1,"description":"","link":"https:\/\/blogs.ubc.ca\/collaborativesustainabilityedu\/category\/contact\/","name":"contact","slug":"contact","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ubc.ca\/collaborativesustainabilityedu\/wp-json\/wp\/v2\/categories\/4033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ubc.ca\/collaborativesustainabilityedu\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.ubc.ca\/collaborativesustainabilityedu\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.ubc.ca\/collaborativesustainabilityedu\/wp-json\/wp\/v2\/posts?categories=4033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}