{"id":6291,"count":5,"description":"Work 3 work","link":"https:\/\/blogs.ubc.ca\/collinsamy\/category\/assignment-3\/","name":"Assignment 3","slug":"assignment-3","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ubc.ca\/collinsamy\/wp-json\/wp\/v2\/categories\/6291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ubc.ca\/collinsamy\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.ubc.ca\/collinsamy\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.ubc.ca\/collinsamy\/wp-json\/wp\/v2\/posts?categories=6291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}