{"id":42,"name":"Brian Powell","url":"","description":"","link":"https:\/\/blogs.ubc.ca\/etec522sept09\/author\/bpowell\/","slug":"bpowell","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ubc.ca\/etec522sept09\/wp-json\/wp\/v2\/users\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ubc.ca\/etec522sept09\/wp-json\/wp\/v2\/users"}]}}