{"id":3574,"count":1,"description":"","link":"https:\/\/blogs.ubc.ca\/etec540sept09\/tag\/archive\/","name":"archive","slug":"archive","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ubc.ca\/etec540sept09\/wp-json\/wp\/v2\/tags\/3574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ubc.ca\/etec540sept09\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.ubc.ca\/etec540sept09\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.ubc.ca\/etec540sept09\/wp-json\/wp\/v2\/posts?tags=3574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}