{"id":1243,"date":"2006-05-22T09:08:50","date_gmt":"2006-05-22T17:08:50","guid":{"rendered":"https:\/\/blogs.ubc.ca\/peru\/2006\/05\/22\/presidential-debate-analysis-by-themes\/"},"modified":"2006-05-22T09:08:50","modified_gmt":"2006-05-22T17:08:50","slug":"presidential-debate-analysis-by-themes","status":"publish","type":"post","link":"https:\/\/blogs.ubc.ca\/peru\/2006\/05\/22\/presidential-debate-analysis-by-themes\/","title":{"rendered":"Presidential Debate: Analysis by Themes"},"content":{"rendered":"<p><!--more--><br \/>\n<em><strong><a href=\"http:\/\/www.larepublica.com.pe\/index.php?option=com_content&amp;task=view&amp;id=111412&amp;Itemid=483&amp;fecha_edicion=2006-05-22\">DEMOCRACIA, GOBERNABILIDAD Y DDHH: Alan se olvid\u00f3 de los derechos humanos<\/a><br \/>\nPor Milagros Salazar<br \/>\nLa Republica, 22 de mayo del 2006<\/strong><br \/>\nPrefiri\u00f3 callar. Alan Garc\u00eda no se anim\u00f3 a repetir en el debate presidencial lo que su plan de gobierno se\u00f1ala escuetamente sobre el respeto de los derechos humanos y la sanci\u00f3n a los responsables de su violaci\u00f3n.<br \/>\nEn el primer bloque de su encuentro con Ollanta Humala, Garc\u00eda opt\u00f3 por postular una democracia social en la que se respete la libertad de expresi\u00f3n y se rechace el autoritarismo con el claro prop\u00f3sito de hincar el lado m\u00e1s d\u00e9bil de su adversario.<br \/>\nEn vez de fijar su posici\u00f3n sobre la defensa de los derechos humanos, Garc\u00eda reiter\u00f3 que estar\u00eda dispuesto a aprobar la pena de muerte para los violadores de menores. El l\u00edder aprista prefiri\u00f3 centrar su discurso en derechos como el acceso al agua, el empleo, la educaci\u00f3n y la administraci\u00f3n de justicia.<br \/>\nAl estilo del presidente brasile\u00f1o Luiz Inacio Lula da Silva, Garc\u00eda habl\u00f3 de &#8220;hambre cero&#8221; y &#8220;analfabetismo cero&#8221; como condiciones para garantizar la gobernabilidad.Pero no dijo ni una sola palabra sobre la necesidad de cumplir con las recomendaciones de la CVR.<br \/>\nReparaciones<br \/>\nAl igual que en su plan de gobierno, Ollanta Humala s\u00ed habl\u00f3 de reparaciones materiales e individuales para las v\u00edctimas de la violencia y con este prop\u00f3sito se comprometi\u00f3 a otorgar 150 millones de soles durante los pr\u00f3ximos diez a\u00f1os. A diferencia de sus propuestas en el papel sobre este punto, Humala aterriz\u00f3 en las cifras.<br \/>\nTras mencionar a adversidades cotidianas a las que se enfrentan los sectores populares como el hecho de vivir con S\/.3.50 al d\u00eda, Humala insisti\u00f3 en instaurar una nueva Constituci\u00f3n para garantizar una mejor repartici\u00f3n del poder. Pese a ello, ning\u00fan candidato sorprendi\u00f3 con nuevas propuestas en el primer bloque. Prim\u00f3 el silencio. Ni Humala le habl\u00f3 a Garc\u00eda de la matanza de Cayara ni \u00e9ste le record\u00f3 lo de Madre M\u00eda.<br \/>\nAN\u00c1LISIS<br \/>\nSalom\u00f3n Lerner, Ex presidente de la Comisi\u00f3n de la Verdad: No le conven\u00eda exponer su pasado<br \/>\nNo se esperaba demasiado del debate, pero lo que ocurri\u00f3 estuvo mucho m\u00e1s lejos de esa realidad. El silencio de Alan Garc\u00eda sobre las recomendaciones de la CVR ha sido consciente para no exponer su pasado y el de Luis Giampietri. Habl\u00f3 de democracia y defendi\u00f3 derechos de segunda generaci\u00f3n, como el acceso a la educaci\u00f3n y la salud, pero no dijo nada sobre un derecho primario como la vida.<br \/>\nPor la inconsistencia con que sustent\u00f3 lo de la CVR, no creo que Ollanta Humala haya le\u00eddo el informe final. Habl\u00f3 de reparaciones como si \u00e9stas se pudieran canjear por el derecho a la justicia A pesar de eso, \u00e9l estuvo bastante mejor que Garc\u00eda en este tema.<br \/>\n<strong><a href=\"http:\/\/www.elcomercioperu.com.pe\/EdicionImpresa\/Html\/2006-05-22\/ImpTemaDia0509682.html\">Democracia, gobernabilidad y derechos humanos: V\u00edas distintas para alcanzar la paz social<\/a><br \/>\nEl Comercio, 22 de mayo del 2006<\/strong><br \/>\nEl Apra busca fortalecer las instituciones y UPP quiere un cambio en la estructura de poder&#8212;Walter Alb\u00e1n, ex defensor del pueblo<br \/>\n&#8220;Habr\u00e1 gobernabilidad si hay cambio. Y ese cambio vendr\u00e1 con crecimiento econ\u00f3mico, con la inversi\u00f3n nacional y extranjera. No hace falta una asamblea constituyente, sino una concertaci\u00f3n entre todos los actores pol\u00edticos del pa\u00eds&#8221; &#8212;Alan Garc\u00eda<br \/>\n&#8220;Hay que construir el futuro. Eso significa una nueva Constituci\u00f3n y una nueva repartici\u00f3n del poder que incluya al pueblo. Vamos a revisar los contratos con las empresas transnacionales para rescatar nuestros recursos naturales&#8221; &#8212;Ollanta Humala<br \/>\nEl ex defensor del Pueblo Walter Alb\u00e1n Peralta calific\u00f3 de &#8220;gran omisi\u00f3n&#8221; el hecho de que el candidato del Apra no haya incluido el tema de los derechos humanos en su presentaci\u00f3n ni su postura respecto de las recomendaciones de la Comisi\u00f3n de la Verdad.<br \/>\n&#8220;Esa omisi\u00f3n es realmente preocupante, pues se trata de un personaje que desea gobernar el pa\u00eds&#8221;, coment\u00f3.<br \/>\nRescat\u00f3, en cambio, que el l\u00edder aprista haya destacado que la gobernabilidad del pa\u00eds implica necesariamente una adecuada paz social con cambios econ\u00f3micos responsables que le permitan al Per\u00fa crecer a un ritmo del 7% del PBI, como en otras latitudes.<br \/>\nEl ex defensor del Pueblo opin\u00f3 que Garc\u00eda &#8220;ha planteado una apuesta definida por la mejora de la econom\u00eda del pa\u00eds, poniendo al desempleo y a la lucha contra la pobreza como el primer objetivo de un eventual gobierno suyo&#8221;.<br \/>\nAdem\u00e1s, sostuvo que es importante que haya dejado en claro que &#8220;la gobernabilidad pasa por rechazar todo tipo de autoritarismo, garantizando el equilibrio de los poderes del Estado y una irrestricta libertad de expresi\u00f3n&#8221;.<br \/>\nDe los planteamientos que Garc\u00eda verti\u00f3 en el debate presidencial, Alb\u00e1n rescat\u00f3 otro tema sustantivo: &#8220;Ha propuesto reformas parciales a la Carta Magna y no la convocatoria a una asamblea constituyente, como s\u00ed hizo su oponente de UPP&#8221;.<br \/>\nREFORMA DEL PODER JUDICIAL<br \/>\nAlb\u00e1n sostuvo que el postulante de UPP coincidi\u00f3 con su contendor en el hecho de sustentar la gobernabilidad en la lucha contra la pobreza y la paz social. Sin embargo, hay diferencias.<br \/>\n&#8220;Para alcanzar la gobernabilidad, el postulante de UPP apuesta b\u00e1sicamente por cambios pol\u00edticos profundos, aunque sin detallar adecuadamente sus alcances. Se habla de cambios en la estructura del poder, pero no se se\u00f1alan las implicancias de esa medida&#8221;.<br \/>\nEl jurista se\u00f1al\u00f3 que Ollanta Humala fue lejos en ciertas propuestas, y super\u00f3 al candidato del Apra.<br \/>\n&#8220;Hizo una referencia concreta a una reforma del Poder Judicial y a la decisi\u00f3n de respaldar y ejecutar las recomendaciones de la Comisi\u00f3n de la Verdad&#8221;.<br \/>\nEn todo caso, si bien ambos postulantes lanzaron al ruedo propuestas interesantes, Alb\u00e1n sostiene que algo ha caracterizado el debate presidencial: las ideas han sido muy generales, pues los candidatos no se\u00f1alaron los caminos que van a seguir.<br \/>\nA modo de resumen, el ex defensor del Pueblo sostiene lo siguiente: mientras el candidato del Apra pide reafirmar la institucionalidad del pa\u00eds para alcanzar la paz social y la gobernabilidad, lo contrario pasa con Ollanta Humala, pues UPP propugna cambios en el sistema pol\u00edtico y en la institucionalidad para alcanzar esos objetivos.<br \/>\n<strong><a href=\"http:\/\/www.larepublica.com.pe\/index.php?option=com_content&amp;task=view&amp;id=111411&amp;Itemid=483&amp;fecha_edicion=2006-05-22\">POL\u00cdTICA ECON\u00d3MICA Y LUCHA CONTRA LA POBREZA: M\u00e1s trabajo y menos asistencialismo<\/a><br \/>\nPor Carolina Mart\u00edn<br \/>\nLa Republica, 22 de mayo del 2006<\/strong><br \/>\nSus propuestas en materia econ\u00f3mica se redujeron pr\u00e1cticamente al tema energ\u00e9tico y la promesa de reducir (en mayor o menor medida, seg\u00fan el candidato) el precio del gas y del combustible.<br \/>\nPor primera vez, eso s\u00ed, los dos aspirantes a la Presidencia se\u00f1alaron que la pobreza se combate con el empleo, y eso fue lo que propusieron, adem\u00e1s de mejorar algunos programas sociales como el Vaso de Leche o los Comedores Populares.<br \/>\nOllanta Humala comenz\u00f3 con sus tres temas fuertes en campa\u00f1a: la rebaja del combustible y del gas dom\u00e9stico en un 30% y un 25% respectivamente, la revisi\u00f3n de los contratos con las transnacionales y la revisi\u00f3n del TLC.<br \/>\nY aunque el ex militar lo intent\u00f3 por activa y por pasiva, Alan Garc\u00eda solo le sigui\u00f3 en uno de ellos, los combustibles. El ex presidente tambi\u00e9n dijo que reducir\u00eda el precio de ambos recursos energ\u00e9ticos, pero no tanto como hab\u00eda anunciado su contrincante. Y esgrimi\u00f3 dos motivos de peso: al reducir a 10 soles el precio del gas. Cusco se quedar\u00eda con 50 millones de soles menos en regal\u00edas, y al reducir al 30% el precio de la gasolina se perder\u00edan 5 mil millones de soles, precisamente el monto de las pensiones.<br \/>\nDespu\u00e9s comenz\u00f3 la lluvia de propuestas. Ollanta habl\u00f3 de disminuir la desnutrici\u00f3n cr\u00f3nica de los ni\u00f1os en un 50%, de agua y saneamiento para un mill\u00f3n de personas y de programas para promover los negocios de j\u00f3venes y mujeres emprendedoras a trav\u00e9s de microcr\u00e9ditos.<br \/>\nAlan Garc\u00eda tambi\u00e9n prometi\u00f3 microcr\u00e9ditos para pymes, m\u00e1s becas de estudios, la Sierra Exportadora, Agua para Todos, el impulso de Hambre Cero y la inclusi\u00f3n de 4.5 millones de peruanos en los programas de salud.<br \/>\nAN\u00c1LISIS<br \/>\nPedro Francke, Economista: Falt\u00f3 reforma tributaria<br \/>\n&#8220;Ollanta Humala ha hablado de generalidades sin concretar, mientras que Alan Garc\u00eda se ha quedado m\u00e1s en los detalles. Por ejemplo, Humala ha hecho una gran propuesta de redistribuci\u00f3n de la renta de recursos naturales, y Garc\u00eda ha hablado de cr\u00e9dito juvenil y cr\u00e9dito agrario pero sin expresar una visi\u00f3n m\u00e1s amplia. De econom\u00eda los dos han hablado m\u00e1s bien poco. Nada de reforma tributaria, del BCR, ni de c\u00f3mo enfrentar la deuda externa, ni de c\u00f3mo promover las exportaciones. En seguida se han ido a temas como las madres del Vaso de Leche o la reducci\u00f3n a la mitad de una elevada desnutrici\u00f3n infantil cr\u00f3nica en el Per\u00fa. Lo que me indica el debate es que no tienen una propuesta econ\u00f3mica coherente en sus planes de gobierno. Quiz\u00e1s por el propio formato del debate, no hubo tiempo para exponerla. Pero no me han convencido ninguna de las dos propuestas&#8221;.<br \/>\n<strong><a href=\"http:\/\/www.elcomercioperu.com.pe\/EdicionImpresa\/Html\/2006-05-22\/ImpTemaDia0509683.html\">Pol\u00edtica econ\u00f3mica y lucha contra la pobreza: Diagn\u00f3sticos y planes ya conocidos<\/a><br \/>\nEl Comercio, 22 de mayo del 2006<\/strong><br \/>\n&#8220;Pareci\u00f3 una exposici\u00f3n, pero ninguno explic\u00f3 c\u00f3mo financiar\u00e1 sus propuestas&#8221;&#8212;Eduardo Mor\u00f3n, economista<br \/>\nReduciremos el precio de los combustibles en 30% y el del gas dom\u00e9stico en 25%. Se revisar\u00e1 los contratos de las empresas que no pagan regal\u00edas y los que son lesivos al inter\u00e9s del Estado. Se revisar\u00e1 el TLC&#8212;Ollanta Humala<br \/>\nSe crecer\u00e1 7% al a\u00f1o y el pa\u00eds ser\u00e1 el primero del Pac\u00edfico Sur a trav\u00e9s de un megapuerto, la Interoce\u00e1nica, el gas y la agroexportaci\u00f3n. Se renegociar\u00e1 las tarifas de servicios, como luz o tel\u00e9fono, a trav\u00e9s de los reguladores&#8212;Alan Garc\u00eda<br \/>\n\u00bfFueron claros los candidatos en sus propuestas econ\u00f3micas? Para el economista Eduardo Mor\u00f3n, hubo mucho de fuego artificial y frases que sonaron bien, pero poco sustento, en parte por el formato del debate. &#8220;No parec\u00eda un debate, sino la exposici\u00f3n de dos personas sobre temas totalmente distintos&#8221;, indic\u00f3.<br \/>\nSin embargo, en lo que concierne a los temas de fondo, Mor\u00f3n consider\u00f3 que Garc\u00eda y Humala quedaron en deuda.<br \/>\n&#8220;En varios temas, los diagn\u00f3sticos han estado bien en ambos candidatos, pero las propuestas han sido malas. En otros casos, las propuestas ni siquiera se sustentaron con un diagn\u00f3stico adecuado&#8221;.<br \/>\nSobre la propuesta humalista de reducir los precios de los combustibles y del gas, en 30% y 25%, respectivamente, el economista opin\u00f3 que &#8220;en la forma que \u00e9l lo plantea, tener energ\u00eda cara hace que cueste m\u00e1s integrar a la poblaci\u00f3n. Me parece que hay muchos costos que probablemente son mayores y que son m\u00e1s f\u00e1ciles de reducir que los combustibles, sin perjuicio en los ingresos fiscales&#8221;.<br \/>\nEn general, dicha propuesta es efectista e irreal, manifest\u00f3.<br \/>\nSeg\u00fan el economista, ninguno explic\u00f3 la forma como financiar\u00e1n sus planes, pese a la profusi\u00f3n de programas y cr\u00e9ditos prometidos.<br \/>\n&#8220;El Apra us\u00f3 la herramienta de bajar los salarios de la administraci\u00f3n p\u00fablica para ahorrar 400 millones de soles. Mas saben que no lo pueden hacer, pues sencillamente no tendr\u00edamos una administraci\u00f3n p\u00fablica de calidad. Los mejores se ir\u00edan del Estado&#8221;.<br \/>\nY sobre el tema de las pensiones, Mor\u00f3n enfatiz\u00f3 que la gran propuesta de ambos candidatos es la libre desafiliaci\u00f3n de las AFP. &#8220;Sin embargo, dicha medida no solucionar\u00e1 el gran problema de que miles de personas no tengan cobertura previsional&#8221;, dijo.<br \/>\nCONTRAPUNTO FLOJO<br \/>\nEl economista Efra\u00edn Gonzales de Olarte sostuvo que, en l\u00edneas generales, el debate fue pobre y no esclareci\u00f3 a la poblaci\u00f3n lo que ya se viene discutiendo.<br \/>\n&#8220;Casi no hubo debate, cada uno habl\u00f3 de lo que ya se conoc\u00eda de sus planes de gobierno y no hubo un contrapunto sobre temas esenciales, como el modelo econ\u00f3mico. El debate fue en realidad bastante flojo y no se escuch\u00f3 cosas importantes&#8221;.<br \/>\nAdem\u00e1s, cuestion\u00f3 que exista una terrible confusi\u00f3n entre los t\u00e9rminos descentralizaci\u00f3n y regionalizaci\u00f3n, sobre todo por parte de Humala.<br \/>\nConsider\u00f3 poco claros los discursos sobre pol\u00edtica social, econ\u00f3mica y de derechos humanos, debido a que no hubo una adecuada distribuci\u00f3n de los temas.<br \/>\n&#8220;Lamento que no se hablara del tema de desarrollo humano, de c\u00f3mo hacer para expandir las oportunidades y capacidades entre las personas. La gente aparece ac\u00e1 como la clientela a quien hay que convencer para que voten por uno&#8221;, expres\u00f3.<br \/>\n<strong><a href=\"http:\/\/www.larepublica.com.pe\/index.php?option=com_content&amp;task=view&amp;id=111410&amp;Itemid=483&amp;fecha_edicion=2006-05-22\">POL\u00cdTICA SOCIAL Y ANTICORRUPCI\u00d3N: Ollanta en anticorrupci\u00f3n, Alan en lo social<\/a><br \/>\nPor Milagros Salazar<br \/>\nLa Republica, 22 de mayo del 2006<\/strong><br \/>\nLa propuesta fue lanzada con sabor a revancha. Pocos minutos despu\u00e9s de que su contendor le recordara que gan\u00f3 300 mil d\u00f3lares como agregado militar en Francia y Corea del Sur, Ollanta Humala dijo que no permitir\u00e1 que los delitos por corrupci\u00f3n prescriban como sucede con &#8220;ex presidentes que salen de sus gobiernos con cuantiosas propiedades&#8221;.<br \/>\nEl dardo fue directo al pasado de Alan Garc\u00eda, quien fue acusado por enriquecimiento il\u00edcito por malos manejos en su gobierno.<br \/>\n&#8220;Vamos a eliminar la prescripci\u00f3n y quisi\u00e9ramos incluir al se\u00f1or Garc\u00eda para que tenga la posibilidad de limpiar su honor debido a que est\u00e1 cuestionado por el tema de una prescripci\u00f3n&#8221;, apunt\u00f3 el candidato de UPP.<br \/>\nReactivar el Sepa<br \/>\nComo parte de una cruzada nacional anticorrupci\u00f3n, Humala reiter\u00f3 que realizar\u00e1 una auditor\u00eda a todos los gobiernos regionales. Pero adem\u00e1s anunci\u00f3 que reactivar\u00e1 la colonia penal del Sepa donde los presos pagaban sus penas cultivando la tierra y dedic\u00e1ndose a actividades de colonializaci\u00f3n en la frontera.<br \/>\n&#8220;Ah\u00ed ir\u00e1n en principio nuestros funcionarios corruptos. As\u00ed que no se vayan a sorprender si en el corto plazo pudieran ver a ex presidentes o altos funcionarios emprendiendo un programa que llamamos Selva Emprendedora&#8221;. Para concluir con sus propuestas en la lucha anticorrupci\u00f3n, anunci\u00f3 que H\u00e9ctor Vargas Haya ser\u00eda el jefe de los procuradores.<br \/>\nPero si Humala fue m\u00e1s concreto en el tema anticorrupci\u00f3n, Garc\u00eda tuvo mejor performance en propuestas sobre pol\u00edtica social. Se comprometi\u00f3 a aumentar cada a\u00f1o en 0.25% del PBI el presupuesto del sector Educaci\u00f3n, reducir a la mitad los salarios de los funcionarios, eliminar sustancialmente el sueldo de los asesores y la publicidad estatal. Y ambos coincidieron en la libre desafiliaci\u00f3n de las AFP y el respeto a las 8 horas de trabajo.<br \/>\nAN\u00c1LISIS<br \/>\nRonald Gamarra, Ex procurador anticorrupci\u00f3n: Faltaron medidas m\u00e1s concretas<br \/>\n&#8220;Ninguno de los candidatos habl\u00f3 de una pol\u00edtica nacional anticorrupci\u00f3n. No se presentaron medidas concretas sobre prevenci\u00f3n y reprensi\u00f3n de delitos con la repotenciaci\u00f3n de los juzgados anticorrupci\u00f3n ni mucho menos mecanismos para garantizar la transparencia de los presupuestos p\u00fablicos.<br \/>\nSe debi\u00f3 plantear nuevas funciones para que la Contralor\u00eda pueda cumplir una labor efectiva. Hay varios vac\u00edos, aunque Humala fue el \u00fanico que incluy\u00f3 el tema de la imprescriptibilidad de los delitos, a pesar que no supo tratarlo de manera adecuada. De otro lado, lo de reactivar el Sepa me parece inviable&#8221;.<br \/>\n<strong><a href=\"http:\/\/www.elcomercioperu.com.pe\/EdicionImpresa\/Html\/2006-05-22\/ImpTemaDia0509684.html\">Pol\u00edtica anticorrupci\u00f3n: M\u00e1s austeridad y menos prescripci\u00f3n<\/a><br \/>\nEl Comercio, 22 de mayo del 2006<\/strong><br \/>\n&#8220;Es interesante plantear reducir el gasto y que no prescriban los delitos, pero hay que concretarlo&#8221;&#8212;Luis Vargas Valdivia, ex procurador<br \/>\nHaremos un gobierno amplio y eso garantiza que no habr\u00e1 sectarismo. El contralor lo propondr\u00e1 la oposici\u00f3n. Se promover\u00e1 la austeridad con las compras electr\u00f3nicas, as\u00ed se reducir\u00e1 el dispendio y se luchar\u00e1 contra la corrupci\u00f3n&#8212;Alan Garc\u00eda<br \/>\nJam\u00e1s se ha perseguido a los grandes corruptos y se ha dejado que juicios en agravio del Estado prescriban. En nuestro gobierno vamos a eliminar la prescripci\u00f3n y a reactivar el centro de reclusi\u00f3n del Sepa para los funcionarios corruptos&#8212;Ollanta Humala<br \/>\nLuis Vargas Valdivia, ex procurador ad hoc para los casos de Fujimori y Montesinos, reconoci\u00f3 como interesantes algunos de los conceptos esbozados por ambos candidatos presidenciales en cuanto a la pol\u00edtica de control, si bien defini\u00f3 que quien aterriz\u00f3 un poco m\u00e1s en el tema fue el representante del Apra.<br \/>\n&#8220;Me pareci\u00f3 interesante la propuesta de reducci\u00f3n de gasto que hizo Alan Garc\u00eda y la idea de dar mayor transparencia a las adquisiciones mediante el impulso de las compras electr\u00f3nicas&#8221;, puntualiz\u00f3.<br \/>\nEn el postulante de UPP se\u00f1al\u00f3 como plausible la propuesta de hacer imprescriptibles los juicios por corrupci\u00f3n, la cual sugiri\u00f3 afinar m\u00e1s.<br \/>\n&#8220;Hay que tener cuidado con aquello de reactivar el Sepa, recordemos que ese penal fue clausurado porque presentaba un tratamiento infrahumano para los reclusos. El traslado de detenidos debe responder a pol\u00edticas de calificaci\u00f3n y de respeto a los derechos humanos, por m\u00e1s execrable que sea el delito cometido. Pero insisto en que el tema de que no prescriban los delitos por corrupci\u00f3n me pareci\u00f3 muy valioso.<br \/>\nHUECOS EN LOS DISCURSOS<br \/>\nLo que s\u00ed ech\u00f3 de menos Vargas Valdivia fue que no se aludiera al establecimiento de pol\u00edticas serias a mediano y largo plazo, tales como el fortalecimiento de instituciones, la reforma del sistema de administraci\u00f3n de justicia, el fortalecimiento de entidades como la contralor\u00eda o qu\u00e9 hacer, por ejemplo, respecto de la Iniciativa Nacional Anticorrupci\u00f3n.<br \/>\n&#8220;No ha habido ideas concretas y eso es algo en lo que esperamos que, a partir de este debate, se puedan explayar los candidatos en los d\u00edas que restan antes de la segunda vuelta&#8221;.<br \/>\nLA PELEA EMPIEZA ANTES<br \/>\nOtro de los vac\u00edos se\u00f1alados por el ex procurador fue que no se hiciera menci\u00f3n a c\u00f3mo combatir este flagelo desde el comienzo; es decir, desde mucho antes de llegar a la administraci\u00f3n p\u00fablica.<br \/>\n&#8220;No podemos apuntar a una pol\u00edtica de lucha anticorrupci\u00f3n si ello no va aunado al reforzamiento de sistemas educativos. Desde el colegio hay que educar a los ni\u00f1os y j\u00f3venes en lo que es la lucha contra la corrupci\u00f3n. Se trata de reforzar no solo sus valores, sino los conceptos de ciudadan\u00eda que se vienen perdiendo debido al recorte en los programas educativos. Tal cosa es fundamental y crucial porque la lucha anticorrupci\u00f3n no supone \u00fanicamente aumentar las penas&#8221;, subray\u00f3.<br \/>\nVargas Valdivia consider\u00f3 que el escaso tiempo dedicado al tema impidi\u00f3 una mayor aplicaci\u00f3n de los contendores, pero repiti\u00f3 que la lucha contra la corrupci\u00f3n a mediano y a largo plazo requiere planes concretos, m\u00e1s all\u00e1 de los discursos y las iniciativas enarboladas anoche.<br \/>\n<strong><a href=\"http:\/\/www.larepublica.com.pe\/index.php?option=com_content&amp;task=view&amp;id=111413&amp;Itemid=483&amp;fecha_edicion=2006-05-22\">DESCENTRALIZACI\u00d3N: Ollanta asume regionalizaci\u00f3n aprista<\/a><br \/>\nPor Carolina Mart\u00edn<br \/>\nLa Republica, 22 de mayo del 2006<\/strong><br \/>\nQuiz\u00e1s para corroborar su recientemente declarada admiraci\u00f3n por V\u00edctor Ra\u00fal Haya de la Torre, Ollanta Humala Tasso enarbol\u00f3 como bandera durante el debate presidencial una propuesta sobre descentralizaci\u00f3n no incluida en su plan de gobierno, pero s\u00ed en el de su rival, Alan Garc\u00eda P\u00e9rez.<br \/>\nEl militar en retiro afirm\u00f3 creer en la descentralizaci\u00f3n basada en una regionalizaci\u00f3n transversal, una proposici\u00f3n que el ex presidente Garc\u00eda se apresur\u00f3 a recordarle que era una propuesta aprista desde el a\u00f1o 1930.<br \/>\nA partir de esta aseveraci\u00f3n las propuestas del candidato de UPP se repartieron entre las generalidades y los contraataques a una batalla que \u00e9l mismo inici\u00f3 al insinuar que si Montesinos pudiera votar lo har\u00eda por su contrincante. Un tema para el que Humala dedic\u00f3 \u00edntegramente su tiempo de r\u00e9plica y parte de su d\u00faplica. Lo resaltante en este punto fue la sensaci\u00f3n de debilidad que dej\u00f3 Garc\u00eda. Le falt\u00f3 ser m\u00e1s en\u00e9rgico frente al caso Montesinos.<br \/>\nHumala tambi\u00e9n habl\u00f3 de otorgar al Callao el estatus de regi\u00f3n, de crear mecanismos de fiscalizaci\u00f3n de los gobiernos regionales, de eliminar las prefecturas y subprefecturas a fin de ahorrar para las regiones 50 millones de soles, y elegir a los presidentes regionales democr\u00e1ticamente y no &#8220;de forma asamble\u00edsta&#8221;.<br \/>\nEl l\u00edder del Apra prometi\u00f3 incrementar el canon minero, descentralizar el Sistema Nacional de Inversi\u00f3n P\u00fablica (SNIP) que &#8220;ha bloqueado los proyectos de las regiones durante a\u00f1os&#8221;, exonerar a los municipios del pago del 19% del IGV en sus obras, y que el Pronaa y el Foncodes sean gestionados localmente. Aclar\u00f3 a Humala que los jefes regionales no se eleg\u00edan en asambleas. Propuestas de los dos candidatos que no fueron contundentes. &#8220;Lo \u00fanico que queda claro es que ninguno de los dos impulsar\u00e1 el actual proceso de descentralizaci\u00f3n&#8221;, expres\u00f3 Javier Igu\u00ed\u00f1iz.<br \/>\nAN\u00c1LISIS<br \/>\nJavier Azpur, Investigador de Propuesta Ciudadana: &#8220;Hubo vac\u00edos program\u00e1ticos&#8221;<br \/>\n&#8220;Ambos han resaltado la idea de una conformaci\u00f3n de regiones basada en la transversalidad, pero las propuestas de Alan Garc\u00eda han sido m\u00e1s claras, mientras que Ollanta Humala habl\u00f3 de manera m\u00e1s general. Tambi\u00e9n hay que destacar, eso s\u00ed, grandes vac\u00edos en las dos exposiciones. Ninguno de los candidatos ha hablado de c\u00f3mo se va a hacer esa regionalizaci\u00f3n que pregonan, ni de impulsar los proyectos compartidos entre varios departamentos. Tampoco han hablado de la transferencia de funciones y competencias a las regiones, m\u00e1s all\u00e1 de las transferencias de recursos, un gran vac\u00edo que generar\u00eda un gran d\u00e9ficit fiscal&#8221;.<br \/>\n<strong><a href=\"http:\/\/www.elcomercioperu.com.pe\/EdicionImpresa\/Html\/2006-05-22\/ImpTemaDia0509685.html\">Descentralizaci\u00f3n: Falta planificaci\u00f3n y sobra concentraci\u00f3n<\/a><br \/>\nEl Comercio, 22 de mayo del 2006<\/strong><br \/>\n&#8220;Los dos han reconocido que la estructura departamental no es la m\u00e1s adecuada para el Per\u00fa&#8221;&#8212;Javier Azpur, investigador de propuesta ciudadana<br \/>\nCreo en la descentralizaci\u00f3n transversal en el pa\u00eds, aquella que permita democratizar el poder econ\u00f3mico y pol\u00edtico; el pa\u00eds est\u00e1 concentrado en la capital y la costa y eso no permite la soluci\u00f3n de problemas como el empleo&#8212;Ollanta Humala<br \/>\nDe lo que tienen los gobiernos regionales, solo el 5% es para inversi\u00f3n, el resto se va en planillas, por ello no ha habido un verdadero proceso de cambio en el pa\u00eds. Adem\u00e1s, no puede haber descentralizaci\u00f3n sin planificaci\u00f3n&#8212;Alan Garc\u00eda<br \/>\nEspecialista en temas de descentralizaci\u00f3n y uno de los expertos convocados por el Centro de Investigaci\u00f3n Econ\u00f3mica y Social (CIES), Javier Azpur salud\u00f3 que ambos candidatos a la presidencia hayan ratificado la idea de construir regiones en el pa\u00eds.<br \/>\n&#8220;Ese es el primer elemento rescatable. Si bien no lo se\u00f1alaron expl\u00edcitamente, los dos reconocen que la estructura departamental no es la m\u00e1s adecuada y que se requiere avanzar a un proceso de modificaci\u00f3n del ordenamiento territorial en el pa\u00eds&#8221;, dijo Azpur al hacer su an\u00e1lisis de lo escuchado anoche.<br \/>\n&#8220;En el caso de Alan Garc\u00eda, ha sido positivo el \u00e9nfasis puesto en iniciar la descentralizaci\u00f3n fiscal y esta idea de una mayor transferencia de recursos, pero hay que saber c\u00f3mo est\u00e1 pensando llevar adelante tal propuesta, porque la descentralizaci\u00f3n fiscal debe ir acompa\u00f1ada por un proceso de transferencia de competencias; es decir, no se puede transferir recursos si no se traspasan antes competencias y funciones a los gobiernos regionales y locales, y ese es un punto que ninguno de los dos candidatos abord\u00f3&#8221;, advirti\u00f3.<br \/>\nAzpur lament\u00f3 que Ollanta Humala hubiera dedicado el tiempo de su d\u00faplica en este cuarto aspecto tem\u00e1tico del debate al tema del presunto favoritismo de Vladimiro Montesinos hacia Garc\u00eda, por lo cual perdi\u00f3 valiosos dos minutos para desenrollar sus planes.<br \/>\n&#8220;Garc\u00eda abord\u00f3 con mayor tiempo el tema y puso algunos puntos m\u00e1s en agenda, que en el caso de Humala no lograron concretarse&#8221;, compar\u00f3.<br \/>\nPARA PLANEAR MEJOR<br \/>\nOtro de los puntos que resalt\u00f3 Azpur de la pr\u00e9dica del l\u00edder del partido de la estrella fue el fortalecimiento del Centro de Planeamiento Estrat\u00e9gico (Ceplan)<br \/>\n&#8220;Considero que es una buena propuesta, porque este proceso requiere una transformaci\u00f3n en la conducci\u00f3n del proceso y ese es un vac\u00edo que no ha sido abordado directamente. El Consejo Nacional de Descentralizaci\u00f3n (CND) ha mostrado sus l\u00edmites, hay que repensarlo y una buena base de partida es colocar el Ceplan como eje articulador, por cuanto tambi\u00e9n interesa vincular el plan nacional de desarrollo con los planes regionales y locales&#8221;, agreg\u00f3.<br \/>\nEn donde Azpur encontr\u00f3 un feliz punto de coincidencia fue en que los dos contrincantes se\u00f1alaron que habr\u00e1 una mayor disponibilidad de recursos para la inversi\u00f3n en infraestructura.<br \/>\n&#8220;Eso s\u00ed, espero que durante el debate t\u00e9cnico se se\u00f1ale cu\u00e1les son los proyectos de inversi\u00f3n prioritarios &#8211;algunos como la construcci\u00f3n de la v\u00eda Interoce\u00e1nica ya han sido se\u00f1alados&#8211;, porque no se trata de inversiones en abstracto, eso est\u00e1 claro&#8221;.<br \/>\n\u00bfY LA GENTE D\u00d3NDE EST\u00c1?<br \/>\nEn lo que hubo un jal\u00f3n de orejas para Garc\u00eda y Humala, fue &#8211;a juicio de Azpur&#8211; en el aspecto de participaci\u00f3n ciudadana.<br \/>\n&#8220;Ese tema no ha sido tocado y eso que se trata de un elemento fundamental, porque se trata del involucramiento de la poblaci\u00f3n y de las organizaciones sociales en la gesti\u00f3n p\u00fablica. No se puede desatender ello&#8221;, anot\u00f3.<br \/>\nFinalmente, Azpur dijo que se omiti\u00f3 decir c\u00f3mo se har\u00e1 para que las empresas e industrias extractivas canalicen sus mayores recursos hacia los gobiernos regionales y locales, sin afectar las existencias disponibles en el Gobierno Central para aquellas regiones que no se benefician con la miner\u00eda o el petr\u00f3leo.<br \/>\n<strong><a href=\"http:\/\/www.larepublica.com.pe\/index.php?option=com_content&amp;task=view&amp;id=111414&amp;Itemid=483&amp;fecha_edicion=2006-05-22\">SEGURIDAD CIUDADANA: No revelaron c\u00f3mo se har\u00e1n las reformas<\/a><br \/>\nPor Luis Vel\u00e1squez<br \/>\nLa Republica, 22 de mayo del 2006<\/strong><br \/>\nLas improvisaciones y promesas respecto a la seguridad ciudadana abundaron durante el debate. Pero falt\u00f3 lo m\u00e1s importante: decir c\u00f3mo y cu\u00e1ndo har\u00edan realidad sus ofertas. Empez\u00f3 Alan Garc\u00eda ofreciendo ampliar el n\u00famero de polic\u00edas y proponiendo la cadena perpetua para los secuestradores y asesinos de ni\u00f1os.<br \/>\nLuego le toc\u00f3 el turno a Ollanta Humala, quien propuso repotenciar las rondas campesinas y comit\u00e9s de autodefensa en las zonas rurales, as\u00ed como reubicar a los polic\u00edas de estos sectores envi\u00e1ndolos a otras jurisdicciones.<br \/>\nDesconocen la ley<br \/>\nM\u00e1s tarde ambos ofrecieron m\u00e1s presupuesto y apoyo, sin detallar de qu\u00e9 manera lo har\u00edan. Hasta que les toc\u00f3 hablar de la reorientaci\u00f3n de la seguridad ciudadana. En ese momento ambos candidatos, pero sobre todo Ollanta Humala, demostraron desconocer que ya hay un conductor de esta lucha y que hay una ley que la reglamenta. Para muestra un bot\u00f3n: Ollanta propone otorgar este rol a los alcaldes, y Garc\u00eda ofrece convertir este tema en una pol\u00edtica de Estado, cuando esto ya ha sido establecido por una ley (la 27933, de 2003), la cual establece que son los alcaldes, los presidentes regionales y el ministro del Interior los responsables de conducir la seguridad ciudadana en sus jurisdicciones.<br \/>\n<strong>AN\u00c1LISIS<br \/>\nGino Costa S., Ex ministro del Interior: Solo lanzaron ofertas efectistas<\/strong><br \/>\nEndurecer las penas, como propone Alan Garc\u00eda, o relanzar las rondas campesinas como ofrece Humala, son medidas efectistas que buscan conseguir votos, pero no son los temas importantes que se esperaban. Ninguno habl\u00f3 de la prevenci\u00f3n, por ejemplo, o de reformas institucionales, que son temas pendientes y urgentes. Porque no se trata \u00fanicamente de otorgar mayores recursos a la Polic\u00eda. Hay que solucionar primero los problemas internos de la instituci\u00f3n policial que son tan o m\u00e1s importantes que los reequipamientos o relanzamientos. Todos estamos de acuerdo en apoyar a la Divise, pero c\u00f3mo lo hacemos.<br \/>\n<strong><a href=\"http:\/\/www.elcomercioperu.com.pe\/EdicionImpresa\/Html\/2006-05-22\/ImpTemaDia0509686.html\">Seguridad ciudadana: Candidatos confundieron algunos conceptos<\/a><br \/>\nEl Comercio, 22 de mayo del 2006 <\/strong><br \/>\n&#8220;Garc\u00eda eliminar\u00e1 beneficios carcelarios. Para Humala, las prisiones deben rehabilitar&#8221;&#8212;Gabriel Prado, experto del instituto de defensa legal (IDL)<br \/>\nNo vamos a destruir la PNP, para repartirla entre 1.800 municipios del pa\u00eds. Por el contrario, vamos a equiparla. Habr\u00e1 m\u00e1s efectivos PNP en las calles y las labores administrativas se pondr\u00e1n a cargo de un servicio civil&#8212;Alan Garc\u00eda<br \/>\nLos comit\u00e9s de autodefensa y las rondas campesinas se han fajado contra el terrorismo. Por eso tienen que entrar en el sistema de seguridad ciudadana, para que el personal PNP pueda ir a trabajar a zonas alejadas del pa\u00eds&#8212;Ollanta Humala<br \/>\nGabriel Prado es especialista en seguridad ciudadana del Instituto de Defensa Legal (IDL).  Su an\u00e1lisis empieza con el postulante del Apra: &#8220;Se debe resaltar que Alan Garc\u00eda haya reconocido que la lucha contra la delincuencia es una exigencia de la sociedad y que la seguridad ciudadana va a ser definitivamente una pol\u00edtica de Estado y no solamente un tema sectorial&#8221;.<br \/>\nY agrega: &#8220;Otro hecho importante es que haya aclarado que no se va a desmembrar la PNP, sino que su plan de gobierno se va a orientar a repotenciar y fortalecer a dicha instituci\u00f3n&#8221;.<br \/>\nEl especialista del IDL resalta el diagn\u00f3stico del postulante del Apra respecto a la carencia de efectivos PNP en el territorio nacional, junto a la eliminaci\u00f3n de ciertos beneficios penitenciarios para los delincuentes avezados y reincidentes que pueblan las c\u00e1rceles del pa\u00eds.<br \/>\nPero hubo una propuesta lamentable, de acuerdo con Gabriel Prado: &#8220;Defender la pena de muerte para violadores y otros criminales es reprobable, pues se ha comprobado que la pena capital no resuelve los problemas de la sociedad&#8221;.<br \/>\nEl especialista del IDL tiene la siguiente opini\u00f3n: &#8220;Sin duda, fue un planteamiento populista. Ojal\u00e1 no se aplique en un hipot\u00e9tico gobierno suyo&#8221;.<br \/>\nPero hubo otras zonas oscuras que el postulante del Apra dej\u00f3 al descubierto: &#8220;al final Alan Garc\u00eda plante\u00f3 reforzar la Dircote, cuando esa instituci\u00f3n nada tiene que ver con la seguridad ciudadana. Esa confusi\u00f3n de conceptos es grave para alguien que desea llegar a Palacio de Gobierno&#8221;.<br \/>\n&#8220;Tampoco hizo referencia al sistema penitenciario (INPE) que se encuentra en crisis o a las pol\u00edticas sociales que se necesitan para prevenir el delito&#8221;.<br \/>\nEl experto del IDL destaca que Garc\u00eda P\u00e9rez haya sido espec\u00edfico en resaltar que el liderazgo de la lucha contra la delincuencia siempre debe encontrarse en manos de la autoridad civil y pol\u00edtica&#8221;.<br \/>\nDEFICIENCIAS EN UPP<br \/>\nGabriel Prado sostiene que el candidato de UPP dijo muchas cosas desconcertantes: &#8220;Parece que Ollanta Humala no ha le\u00eddo la Ley 27933 del sistema nacional de seguridad ciudadana&#8221;.<br \/>\nY agrega: &#8220;El postulante de UPP sostiene que la ley 27933 no especifica el liderazgo de la lucha contra la delincuencia. Debe saber que son los alcaldes los encargados de ejecutar esa importante norma&#8221;.<br \/>\nTambi\u00e9n critic\u00f3 la propuesta de vincular con la seguridad ciudadana los comit\u00e9s de autodefensa campesina y las rondas campesinas: &#8220;Es un lamentable error, pues su accionar corresponde a un contexto distinto. Los comit\u00e9s de autodefensa y las rondas campesinas lucharon contra el terrorismo, lo que nada tiene que ver con la seguridad en las calles.<br \/>\nGabriel Prado sostiene que Ollanta Humala debi\u00f3 referirse concretamente a las juntas vecinales, como encargadas de ese tema, pero no fue as\u00ed.<br \/>\nPero eso no es todo: &#8220;\u00bfC\u00f3mo va a se\u00f1alar que va a potenciar a la PNP rural? Que yo sepa, no existe la PNP rural. Otra cosa que preocupa es que proponga procesos r\u00e1pidos en el Poder Judicial, sin manifestar que debe primar el debido proceso y la justicia&#8221;.<br \/>\nEl experto del IDL resalta que Ollanta Humala &#8220;s\u00ed se haya referido a la necesidad de mejorar el sistema penitenciario, como medio de rehabilitaci\u00f3n y resocializaci\u00f3n&#8221;.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1305,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7951],"tags":[],"class_list":["post-1243","post","type-post","status-publish","format-standard","hentry","category-political-parties"],"_links":{"self":[{"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/posts\/1243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/users\/1305"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/comments?post=1243"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/posts\/1243\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/media?parent=1243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/categories?post=1243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/tags?post=1243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}