{"id":1438,"date":"2006-06-10T17:19:32","date_gmt":"2006-06-11T01:19:32","guid":{"rendered":"https:\/\/blogs.ubc.ca\/peru\/2006\/06\/10\/alan-garcia-solicita-a-ollanta-humala-cita-concertadora\/"},"modified":"2006-06-10T17:19:32","modified_gmt":"2006-06-11T01:19:32","slug":"alan-garcia-solicita-a-ollanta-humala-cita-concertadora","status":"publish","type":"post","link":"https:\/\/blogs.ubc.ca\/peru\/2006\/06\/10\/alan-garcia-solicita-a-ollanta-humala-cita-concertadora\/","title":{"rendered":"Alan Garc\u00eda solicita a Ollanta Humala cita concertadora"},"content":{"rendered":"<p><!--more--><br \/>\n<em><strong><a href=\"http:\/\/www.larepublica.com.pe\/index.php?option=com_content&amp;task=view&amp;id=113201&amp;Itemid=2&amp;fecha_edicion=2006-06-10\">Alan sorprende y pide a Ollanta una reuni\u00f3n a puerta cerrada<\/a><br \/>\nLa Rep\u00fablica, 10 de junio del 2006. Por Por Enrique Patriau.<\/strong><br \/>\nIMPREVISTO ANUNCIO<br \/>\n\u2022 Virtual presidente electo origina pol\u00e9mica con sus declaraciones<br \/>\n\u2022 Minimiz\u00f3 el hecho de que l\u00edder de UPP se niegue a saludarlo y lo invit\u00f3 a reunirse &#8220;por el bien del pa\u00eds&#8221;<br \/>\n\u2022 Contradice postura de su vicepresidente que llam\u00f3 &#8220;golpista&#8221; a Humala.<br \/>\nAlan Garc\u00eda P\u00e9rez se reencontr\u00f3 con la prensa nacional despu\u00e9s de su elecci\u00f3n como nuevo presidente, y sorprendi\u00f3 con una invitaci\u00f3n p\u00fablica a su ex rival, Ollanta Humala Tasso, para conversar en privado sobre la necesidad de consolidar la democracia peruana.<br \/>\nGarc\u00eda hizo este anuncio a pesar de que el almirante Luis Giampietri, su futuro primer vicepresidente, advirti\u00f3 que Humala tiene la intenci\u00f3n de rebelarse contra el orden legalmente establecido. En otras palabras, de perpetrar un golpe militar, apelando a sus relaciones con reservistas del Ej\u00e9rcito. Pero a diferencia de Giampietri, Garc\u00eda manifest\u00f3 no creer que Humala est\u00e9 inmerso en una &#8220;conspiraci\u00f3n&#8221;.<br \/>\n&#8220;Estoy convencido de que \u00e9l (Ollanta) se ha integrado a la vida democr\u00e1tica, y en la vida democr\u00e1tica tendr\u00e1 grandes posibilidades m\u00e1s adelante&#8221;, explic\u00f3.<br \/>\nLo que dijo Giampietri<br \/>\nM\u00e1s temprano, en declaraciones a una radio local, Giampietri reiter\u00f3 lo dicho un d\u00eda antes: \u201c\u00c9l (Humala) no acepta las reglas de juego de la democracia. Quiere desestabilizar al pa\u00eds, y eso a mi entender es un golpe\u201d.<br \/>\nDebe recordarse tambi\u00e9n que, durante la campa\u00f1a, el l\u00edder aprista tuvo palabras bastante duras contra su par nacionalista. Entre otras cosas, lo calific\u00f3 como \u201casesino de polic\u00edas\u201d.<br \/>\nPero ni la lluvia de adjetivos que arreci\u00f3 en los d\u00edas previos a las elecciones ni el maltrato mutuo se presentan como obst\u00e1culos para que Garc\u00eda intente el acercamiento.<br \/>\nSeg\u00fan precis\u00f3, su llamado a Ollanta es para &#8220;una conversaci\u00f3n a puerta cerrada&#8221; en el camino a lograr &#8220;una concertaci\u00f3n&#8221; o &#8220;una coexistencia en beneficio del pa\u00eds&#8221;. Y luego agreg\u00f3 que, por el bien del pa\u00eds, es capaz de sentarse a la misma mesa \u201ccon cualquiera\u201d.<br \/>\n&#8220;Yo soy el presidente&#8221;<br \/>\nCuando le preguntaron a Garc\u00eda si le preocupaba que Humala se convierta en un factor perturbador, respondi\u00f3 que si bien al ex candidato de UPP le asiste el derecho de opinar, no aceptar\u00e1 amenazas ni conspiraciones.<br \/>\n&#8220;Tampoco creo que ocurra. El se\u00f1or Humala se ha integrado a la vida democr\u00e1tica\u201d, repiti\u00f3.<br \/>\nGarc\u00eda admiti\u00f3 adem\u00e1s que Humala tiene buenas perspectivas electorales para noviembre, cuando se elijan a presidentes regionales y alcaldes, o incluso hacia el 2011; no obstante, record\u00f3 que el nuevo mandatario es \u00e9l.<br \/>\n\u201cY no contar\u00e9 con ning\u00fan ministro fantasma llamado Ollanta Humala\u201d, afirm\u00f3.<br \/>\nSobre el gabinete y el TLC<br \/>\nAyer, Garc\u00eda habl\u00f3 de todo. Por ejemplo, puso fecha definitiva a la presentaci\u00f3n del primer gabinete: el 27 de julio, apenas un d\u00eda antes de recibir la banda presidencial.<br \/>\nAdelant\u00f3 tambi\u00e9n que el perfil que busca para el premierato es el de un \u201cconcertador\u201d capaz de emprender las tareas de gobierno y de construir una mayor\u00eda permanente en el nuevo Congreso.<br \/>\nDe paso, inform\u00f3 que hoy se reunir\u00e1 con las personas que se encargar\u00e1n de la transferencia en las distintas ramas del Estado, aunque advirti\u00f3 que de ning\u00fan modo debe entenderse que los elegidos se convertir\u00e1n en los nuevos ministros.<br \/>\nEn otro momento, ratific\u00f3 medidas de austeridad apenas empiece su mandato, como la reducci\u00f3n de los sueldos p\u00fablicos y del personal asignado a Palacio de Gobierno, al igual que la supresi\u00f3n del despacho de la primera dama.<br \/>\nOtro anuncio fue el &#8220;relanzamiento&#8221; de la Comisi\u00f3n Nacional Anticorrupci\u00f3n y de la figura del zar anticorrupci\u00f3n.<br \/>\nFinalmente, sin aclarar cu\u00e1l ser\u00e1 la posici\u00f3n de la bancada aprista, dijo que no pondr\u00e1 objeciones si el actual Congreso decide aprobar el TLC. Eso s\u00ed, advirti\u00f3 que todo lo que se haga apuradamente puede terminar cost\u00e1ndole m\u00e1s al Per\u00fa.<br \/>\n<strong><a href=\"http:\/\/www.elcomercioperu.com.pe\/EdicionImpresa\/Html\/2006-06-10\/impPolitica0520380.html\">Alan Garc\u00eda pide cita a Humala para dialogar<\/a><br \/>\nEl Comercio, 10 de junio del 2006. Por Jorge Salda\u00f1a Ram\u00edrez.<\/strong><br \/>\nReci\u00e9n el 27 de julio se conocer\u00e1 a integrantes de su primer gabinete. Se eliminar\u00e1 el despacho de primera dama y se reducir\u00e1 el presidencial<br \/>\nEl virtual presidente de la Rep\u00fablica, Alan Garc\u00eda P\u00e9rez, dio ayer tres noticias importantes: cerrar\u00e1 el despacho de la primera dama cuando acceda al poder, reducir\u00e1 a la mitad el personal que labora en el despacho presidencial y reci\u00e9n el pr\u00f3ximo 27 de julio el pa\u00eds conocer\u00e1 qui\u00e9nes ser\u00e1n los integrantes de su primer equipo ministerial.<br \/>\nY para demostrar que lo dicho y hecho durante la campa\u00f1a electoral qued\u00f3 atr\u00e1s, invit\u00f3 p\u00fablicamente a su ex competidor en la segunda vuelta, Ollanta Humala Tasso, para dialogar sobre temas nacionales, debido a que &#8211;seg\u00fan dijo&#8211; los seis millones de votos que el militar en retiro obtuvo el \u00faltimo domingo s\u00ed son respetables.<br \/>\nGarc\u00eda P\u00e9rez apareci\u00f3 ante la prensa nacional cinco d\u00edas despu\u00e9s de conocidos los resultados electorales, que lo colocan nuevamente en la primera magistratura nacional a partir del 28 de julio, y en sus respuestas supo remarcar que gobernar\u00e1 los siguientes cinco a\u00f1os con autoridad y orden de la mano con la m\u00e1s absoluta austeridad fiscal, &#8220;porque la farra es algo impropio y constituye un abuso en detrimento de las grandes mayor\u00edas sociales&#8221;.<br \/>\nGarc\u00eda P\u00e9rez se detuvo un momento al anunciar su invitaci\u00f3n a Humala para conversar, con la finalidad de subrayar que este eventual di\u00e1logo se extiende tambi\u00e9n a la ex candidata presidencial de Unidad Nacional, Lourdes Flores Nano, con quien sostuviera hace muy poco un di\u00e1logo telef\u00f3nico en el cual ella lo salud\u00f3 y felicit\u00f3 por su triunfo electoral.<br \/>\nDijo que as\u00ed como \u00e9l est\u00e1 dispuesto a conversar con sus oponentes pol\u00edticos, el Partido Aprista Peruano tambi\u00e9n debe estar convencido de la necesidad de dialogar con las fuerzas pol\u00edticas opositoras que tienen asiento en el pr\u00f3ximo Congreso de la Rep\u00fablica, aunque tiene claro que &#8220;conversar no es pactar&#8221;.<br \/>\nCuando la prensa quiso arrancarle algunos nombres del eventual primer presidente del Consejo de Ministros de su administraci\u00f3n, Garc\u00eda no solt\u00f3 prenda pero s\u00ed se ratific\u00f3 en que quien ocupe este cargo deber\u00e1 contar con un perfil conciliador, puesto que estar\u00e1 abocado a la pol\u00edtica del d\u00eda a d\u00eda mientras que \u00e9l fijar\u00e1 los grandes lineamientos gubernamentales.<br \/>\nAdelant\u00f3 que hoy convocar\u00e1 a los t\u00e9cnicos apristas que formar\u00e1n parte de los equipos de transferencia de los sectores p\u00fablicos, aunque remarc\u00f3 que no necesariamente sus integrantes ser\u00e1n los titulares de los entes gubernamentales.<br \/>\nEn el tema del Tratado de Libre Comercio (TLC) firmado recientemente entre Per\u00fa y Estados Unidos, Garc\u00eda P\u00e9rez dijo que esta herramienta contractual es parte de las relaciones bilaterales y revel\u00f3 que en el reciente di\u00e1logo telef\u00f3nico que tuvo con el presidente norteamericano, George W. Bush &#8211;con motivo de su triunfo en las urnas electorales&#8211; se plante\u00f3 la conformaci\u00f3n de dos equipos de gobierno para ventilar temas adicionales al contenido general del documento, con el fin de que el TLC sea mucho mejor.<br \/>\nEmpero, no fij\u00f3 posici\u00f3n final acerca de si debe ser este Congreso o el siguiente el que ratifique este tratado bilateral. Sugiri\u00f3, m\u00e1s bien, que el debate parlamentario sea p\u00fablico y lo m\u00e1s continuado posible en las semanas de ampliaci\u00f3n legislativa, que se extender\u00e1 hasta mediados de julio para que la opini\u00f3n p\u00fablica sepa de sus alcances.<br \/>\n<strong><a href=\"http:\/\/www.peru21.com\/P21Impreso\/Html\/2006-06-10\/Politica0520564.html\">Alan le pide a Ollanta entrevista en privado<\/a><br \/>\nPer\u00fa 21, 10 de junio del 2006<\/strong><br \/>\n&#8211; L\u00edder aprista advierte, sin embargo, que gobernar\u00e1 con firmeza y no permitir\u00e1 amenazas.<br \/>\n&#8211; UPP le responde que primero desmienta p\u00fablicamente acusaciones de Giampietri.<br \/>\nCinco d\u00edas despu\u00e9s de la segunda vuelta y de guardar un voluntario silencio, Alan Garc\u00eda enfrent\u00f3 ayer por separado a la prensa nacional y a los corresponsales de medios extranjeros, y aprovech\u00f3 la ocasi\u00f3n para tender puentes que lo acerquen a Ollanta Humala y a las huestes nacionalistas.<br \/>\n&#8220;Las puertas no est\u00e1n cerradas. Invito al se\u00f1or Humala a concederme una entrevista. Se la pide con toda humildad y con todo respeto el presidente electo, que pone a todo el Per\u00fa por encima de cualquier soberbia o de cualquier nominaci\u00f3n o nombramiento que haya recibido&#8221;, le dijo al ex candidato presidencial de UPP desde su b\u00fanker de San Isidro.<br \/>\nEl l\u00edder aprista se\u00f1al\u00f3 que la reuni\u00f3n podr\u00eda realizarse en privado y sin fot\u00f3grafos, &#8220;para que no se cumpla el show medi\u00e1tico&#8221;, y que en ella podr\u00edan conversar sobre sus proyecciones, sus requisitos m\u00ednimos para contribuir a la democracia, a la generaci\u00f3n de empleo y al equilibrio regional de nuestra patria.<br \/>\n&#8220;Yo pongo atr\u00e1s todo lo dicho y hecho. El se\u00f1or Humala ha recibido seis millones de votos, que yo respeto, y por el Per\u00fa estoy dispuesto a sentarme a una mesa con cualquiera. Estoy seguro de que se puede llegar a relaciones, sino de participaci\u00f3n o concertaci\u00f3n, por lo menos de coexistencia. Como dec\u00eda el viejo y sabio Ramiro Prial\u00e9: Conversar no es pactar&#8221;, agreg\u00f3.<br \/>\nGarc\u00eda extendi\u00f3 su invitaci\u00f3n a Lourdes Flores Nano y a los l\u00edderes de las otras fuerzas pol\u00edticas.<br \/>\nGESTOS CLAROS. En el reducto nacionalista, ubicado en la avenida Parque Sur, San Borja, el malestar causado por declaraciones recientes del almirante Luis Giampietri y de Benedicto Jim\u00e9nez era m\u00e1s que evidente, por lo que el llamado a limar asperezas tuvo el efecto contrario y cay\u00f3 como plomo.<br \/>\nJos\u00e9 Vega Antonio, secretario general de UPP, afirm\u00f3 que &#8220;si Garc\u00eda quiere conversar, primero tendr\u00eda que cesar toda la campa\u00f1a contra nuestro l\u00edder Ollanta Humala. Si lo que quieren es un ejercicio democr\u00e1tico, que no sigan insult\u00e1ndonos ni acus\u00e1ndonos de un supuesto alzamiento en armas&#8221;.<br \/>\nVega rechaz\u00f3 una supuesta velada amenaza de Benedicto Jim\u00e9nez, en el sentido de que los servicios de Inteligencia iniciar\u00edan un seguimiento a las actividades de Humala.<br \/>\nCarlos Tapia, vocero personal del l\u00edder nacionalista, descart\u00f3 que se pueda concretar una reuni\u00f3n entre Alan Garc\u00eda y Ollanta Humala sin que antes el l\u00edder aprista desmienta p\u00fablicamente la denuncia de Giampietri, y estim\u00f3 que a quienes no les est\u00e1n dando tregua es a los nacionalistas, &#8220;ya que contin\u00faa la guerra sucia&#8221;.<br \/>\nGonzalo Garc\u00eda tambi\u00e9n se pronunci\u00f3 en el mismo sentido. &#8220;Nosotros hemos sido claros en una reuni\u00f3n con la prensa extranjera, en la cual se\u00f1alamos que no le damos tregua a la lucha contra la corrupci\u00f3n ni a la lucha contra la pobreza&#8221;, insisti\u00f3 el ex candidato a la Primera Vicepresidencia.<br \/>\nNUEVOS FRENTES. El presidente electo tambi\u00e9n se refiri\u00f3 a la tregua al pr\u00f3ximo gobierno, as\u00ed como al anuncio de Humala, en el sentido de que encabezar\u00e1 las protestas contra la aprobaci\u00f3n -en el Congreso- del Tratado de Libre Comercio con Estados Unidos y las demandas laborales.<br \/>\nAlan Garc\u00eda agradeci\u00f3 el gesto de algunos l\u00edderes pol\u00edticos, pero asegur\u00f3 que \u00e9l no es partidario de que se hable de tregua. &#8220;\u00bfC\u00f3mo va a pedir tregua un gobierno que representa a siete millones de votos? El gobierno tiene la obligaci\u00f3n de trabajar, y los que perdieron tienen la obligaci\u00f3n de respetar a los que ganaron y a quien gan\u00f3&#8221;, expres\u00f3.<br \/>\nAgreg\u00f3 que, a pesar de haberse casado dos veces, nunca tuvo luna de miel, as\u00ed que -dijo- no es un tema que le preocupe demasiado. &#8220;No espero la concesi\u00f3n de mis adversarios. Espero que el Estado tenga la capacidad de actuar y de concertar&#8221;, remarc\u00f3.<br \/>\nEl mandatario electo tambi\u00e9n tuvo una posici\u00f3n firme cuando toc\u00f3 el tema de las protestas que enfrentar\u00eda al comenzar su segundo gobierno.<br \/>\n&#8220;El se\u00f1or Humala perdi\u00f3 las elecciones el 4 de junio y no ha sido se\u00f1alado para regir el destino del Per\u00fa. Eso debe quedar muy claro, de manera que no creo que debamos vivir de expectativas y de falsos temores. El pa\u00eds necesita orden y autoridad, y eso lo han pedido tanto mis votantes como los votantes del se\u00f1or Humala&#8221;, precis\u00f3.<br \/>\nManifest\u00f3 luego que Humala tendr\u00e1 su oportunidad, seguramente, en el a\u00f1o 2011, pero que por el momento el Per\u00fa ha tomado una decisi\u00f3n y la har\u00e1 prevalecer. &#8220;No me dejo sobresaltar por ning\u00fan miedo. Tengo el respaldo de siete millones de peruanos y la solvencia suficiente para manejar el Estado&#8221;, apunt\u00f3 finalmente Garc\u00eda.<br \/>\n<strong><a href=\"http:\/\/www.laprimera.com.pe\/noticia.php?IDnoticia=24675\">Garc\u00eda le pide a Humala tener una cita en privado<\/a><br \/>\nPero le advierte que har\u00e1 respetar el resultado de la elecci\u00f3n que le dio el triunfo.<br \/>\nLa Primera, 10 de junio del 2006<\/strong><br \/>\nDijo que a pesar que durante la campa\u00f1a electoral apunt\u00f3 que Humala era un asesino de polic\u00edas, ahora estaba dispuesto a conversar con un l\u00edder pol\u00edtico que en las elecciones pasadas tuvo poco m\u00e1s de tres millones de votos a favor.<br \/>\n\u201cInvito al se\u00f1or Humala a concederme una entrevista. Se la pide con toda humildad y respeto el presidente electo del Per\u00fa.<br \/>\nHumala ha tenido un importante n\u00famero de votos y estoy seguro que se puede llegar a mantener relaciones, si no de participaci\u00f3n o concertaci\u00f3n, por lo menos de coexistencia, que nos permitan hacer lo mejor posible para el Per\u00fa\u201d, acot\u00f3.<br \/>\nNo acepta amenazas<br \/>\nLa singular invitaci\u00f3n es una repuesta a las constantes advertencias que en los \u00faltimos d\u00edas realiz\u00f3 el l\u00edder nacionalista, quien indic\u00f3 que no dar\u00e1 tregua al gobierno aprista debido a que no cree en las palabras del nuevo mandatario.<br \/>\nGarc\u00eda aclar\u00f3 que Humala perdi\u00f3 las elecciones el 4 de junio pasado, por lo que ahora le queda la oportunidad para participar en las elecciones regionales y municipales de noviembre pr\u00f3ximo.<br \/>\n\u201cEl se\u00f1or Humala no ha sido se\u00f1alado para dirigir el destino del pa\u00eds y eso debe quedar muy claro. \u00c9l tendr\u00e1 su oportunidad en el 2011 seguramente y en una muy buena hora democr\u00e1tica. Pero por el momento el pa\u00eds ha tomado una decisi\u00f3n y voy a hacer prevalecer dicha determinaci\u00f3n\u201d, precis\u00f3.<br \/>\nAl recalcar que no gobernar\u00e1 con un ministro fantasma llamado Ollanta Humala Tasso; el virtual presidente anot\u00f3 que no le preocupan los rumores respecto a un intento por desestabilizar su pr\u00f3ximo gobierno.<br \/>\n\u201c\u00c9l tiene todo el derecho de saludar o de no hacerlo, pero no creo que est\u00e9 en intentos de sabotaje, creo que \u00e9l se ha integrado a la vida democr\u00e1tica y en esa vida \u00e9l tendr\u00e1 grandes posibilidades m\u00e1s adelante\u201d, manifest\u00f3, contradiciendo las palabras de su vicepresidente, Luis Giampietri, quien sostiene que Humala estar\u00eda planeando un golpe militar.<br \/>\nNo a la corrupci\u00f3n<br \/>\nAdem\u00e1s Garc\u00eda advirti\u00f3 que su gobierno ser\u00e1 \u201csumamente dr\u00e1stico\u201d con aquellos funcionarios que incurran en tales il\u00edcitos.<br \/>\n\u201cCualquiera que se acerque al gobierno debe saber que ser\u00e1 atacado por el gobierno en caso que caiga en corrupci\u00f3n\u201d, enfatiz\u00f3.<br \/>\nAntes de concluir sus declaraciones tambi\u00e9n se refiri\u00f3 a la ratificaci\u00f3n del Tratado de Libre Comercio y mencion\u00f3 que emitir\u00e1 una opini\u00f3n despu\u00e9s que los congresistas encargados de evaluar ese tema hayan realizado un acucioso an\u00e1lisis sobre el mismo.<br \/>\nReiter\u00f3 que su primer acto de gobierno, apenas asuma el poder, ser\u00e1 reducir el sueldo a aquellos funcionarios que gozan de salarios excesivos.<br \/>\nAusteridad absoluta<br \/>\nDurante la conferencia de prensa convocada ayer, Garc\u00eda hizo hincapi\u00e9 en que no permitir\u00e1 que en su gobierno haya derroches innecesarios.<br \/>\nPor ello prometi\u00f3 que la ceremonia de transmisi\u00f3n de mando no ser\u00e1 fastuosa sino una actividad lo m\u00e1s \u201crepublicana y austera posible\u201d.<br \/>\n\u201cNo quiero que los peruanos paguen un sol de m\u00e1s por el hecho que un presidente le entrega la banda a otro. He revisado los costos de otras transferencias y considero que son absolutamente impropios y abusivos las invitaciones, los cocteles, as\u00ed como el traslado de cientos de personas.<br \/>\nAc\u00e1 simplemente se trata de decir \u2018se\u00f1or, deme la banda que el pueblo le dio antes y yo se la dar\u00e9 al siguiente\u2019. No quiero whisky como si se tratar\u00e1 del r\u00edo Amazonas\u201d, sostuvo.<br \/>\nRevel\u00f3, asimismo, que existe un excesivo n\u00famero de trabajadores que actualmente laboran en Palacio de Gobierno a pesar de que dicho pliego podr\u00eda trabajar s\u00f3lo con la mitad de ellos.<br \/>\n\u201cYa he revisado esas cifras y s\u00e9 que actualmente hay 370 trabajadores estables, fuera de los que laboran eventualmente y pienso que es una exageraci\u00f3n. Yo no soy un reyezuelo de un pa\u00eds tropical que necesito a mucha gente para que me sirva un caf\u00e9\u201d, grafic\u00f3.<br \/>\nAfirm\u00f3 que a pedido de su esposa, Pilar Nores, se suprimir\u00e1 el despacho de la primera dama, as\u00ed como sus asesores, agregados de prensa y asistentes.<br \/>\nEl gabinete<br \/>\nEl virtual presidente Alan Garc\u00eda adelant\u00f3 que reci\u00e9n el pr\u00f3ximo 27 de julio se revelar\u00e1 los nombres de los integrantes del gabinete ministerial. Adelant\u00f3 que hoy dar\u00e1 a conocer los nombres de quienes integran las comisiones de transferencia en los diversos ministerios.<br \/>\n<strong><a href=\"http:\/\/www.larepublica.com.pe\/index.php?option=com_content&amp;task=view&amp;id=113200&amp;Itemid=483&amp;fecha_edicion=2006-06-10\">\u201cNo hay clima para conversar\u201d<\/a><br \/>\nLa Rep\u00fablica, 10 de junio del 2006.  Por Lenka Z\u00e0jec.<\/strong><br \/>\nEntrevista a Gonzalo Garc\u00eda<br \/>\n\u2022 El ex candidato a la primera vicepresidencia por UPP asegura que atender una invitaci\u00f3n del Apra tras las declaraciones de Luis Giampietri y Benedicto Jim\u00e9nez es imposible<br \/>\n\u2022 Niega que el Frente anunciado por Humala sea anti Alan Garc\u00eda.<br \/>\n\u2013Alan Garc\u00eda ha invitado al se\u00f1or Humala a tener una conversaci\u00f3n en privado. \u00bfDeber\u00eda aceptar?<br \/>\n\u2013El se\u00f1or (Benedicto) Jim\u00e9nez ha planteado que se haga un seguimiento al se\u00f1or Humala (por parte de agentes de inteligencia). Ni (Vladimiro) Montesinos, en su mejor momento, tuvo el desparpajo de hacer p\u00fablicos sus seguimientos. Luego, en una segunda declaraci\u00f3n, el se\u00f1or (Luis) Giampietri, procesado por los lamentables hechos de El Front\u00f3n, un especialista en explosivos, dice que se prepara un golpe militar. Evidentemente si se pretende achacar estos hechos a Ollanta, y se suman a ellos las declaraciones con tono descalificador hechas por Del Castillo a La Rep\u00fablica, evidentemente el clima indica que hay una ofensiva del Apra que se parece mucho a las que aplic\u00f3 el Tercer Reich.<br \/>\n\u2013\u00bfEntonces no aceptar\u00e1n la invitaci\u00f3n de Garc\u00eda?<br \/>\n\u2013Despu\u00e9s de que al comandante Humala lo han insultado y sindicado como asesino de polic\u00edas&#8230; no s\u00e9 si habr\u00e1 las mejores condiciones para conversar. Este clima lo han creado (los apristas) para generar el rebote de la prensa. Es una operaci\u00f3n intelectual que consiste en provocar primero un conflicto para luego generar un titular. Eso no tiene otro nombre que sicosocial, al cual uno no tiene por qu\u00e9 prestarse.<br \/>\n\u2013Si es as\u00ed, dir\u00edamos que el sicosocial lo comenz\u00f3 UPP al anunciar un frente nacional, que m\u00e1s parec\u00eda un frente contra Garc\u00eda.<br \/>\n\u2013As\u00ed les habr\u00e1 parecido a quienes militantemente invocan cualquier declaraci\u00f3n del se\u00f1or Humala en esa direcci\u00f3n, pero no a quienes tienen buena fe.<br \/>\n\u2013\u00bfPor qu\u00e9 el se\u00f1or Humala no acepta el triunfo de Garc\u00eda y lo saluda como se suele hacer?<br \/>\n\u2013Sin duda, hay la voluntad de algunos sectores, como el se\u00f1or Jorge del Castillo, que quiere crear un conflicto sobre un gesto. Si esa es la orientaci\u00f3n que quieren recoger ciertos medios cercanos al se\u00f1or Del Castillo u otros, tienen derecho; pero ese (el saludo) es un gesto que exigen algunos medios de prensa solo para la foto.<br \/>\n\u2013\u00bfRespalda el frente nacionalista que impulsa Carlos Tapia?<br \/>\n\u2013No es que lo impulse el se\u00f1or Tapia. Eso est\u00e1 en la p\u00e1gina 3 de nuestro programa y lo hemos planteado hace mucho. Lo \u00fanico que hemos hecho es reiterarlo tras el proceso electoral con el objetivo de acometer la gran transformaci\u00f3n.<br \/>\n\u2013Y oponerse al gobierno de Alan Garc\u00eda&#8230;<br \/>\n\u2013Si el se\u00f1or Garc\u00eda quiere hacerse depositario de la confianza popular, tendr\u00e1 que cumplir con el cambio que prometi\u00f3 y nosotros vamos a ser los fiscalizadores del gobierno para que cumpla.<br \/>\n\u2013Para algunos analistas, m\u00e1s que fiscalizar lo que busca UPP es hacer la vida a cuadros al Apra&#8230;<br \/>\n\u2013\u00bfLa vida a cuadros? Eso ya nos las hizo Alan Garc\u00eda del &#8217;85 al &#8217;90; y no a cuadros&#8230; \u00a1a cuadritos!<br \/>\n\u2013\u00bfNo est\u00e1n dispuestos a dar una tregua a Alan Garc\u00eda?<br \/>\n\u2013Tregua se da a quien est\u00e1 en guerra, y nosotros estamos en guerra contra la pobreza, la miseria y el abuso de las promesas incumplidas. De modo que no podemos m\u00e1s que conciliar si hay voluntad de hacer un r\u00e1pido cambio de las causas que generan esta situaci\u00f3n.<br \/>\n\u2013\u00bfC\u00f3mo ser\u00e1 la relaci\u00f3n del UPP con el Apra en el Congreso?<br \/>\n\u2013Como primera minor\u00eda, seremos fuerza opositora y fiscalizadora, tambi\u00e9n democr\u00e1tica, que impulsar\u00e1 la gran transformaci\u00f3n.<br \/>\n\u2013\u00bfCree que tras los comicios la clase pol\u00edtica y empresarial ha captado el mensaje del pueblo?<br \/>\n\u2013Hay un trabajo que hacer para el futuro y ser m\u00e1s expl\u00edcitos en el sentido de la participaci\u00f3n que deben tener los sectores excluidos.<br \/>\n&#8220;Hay una arremetida contra la izquierda&#8221;<br \/>\n\u2013\u00bfPor qu\u00e9 no se consult\u00f3 al presidente de UPP sobre el Frente Nacionalista Democr\u00e1tico y Popular?<br \/>\n\u2013Aldo Estrada ten\u00eda conocimiento del prop\u00f3sito de la unidad que busca nuestro programa, as\u00ed que no hay nada que extra\u00f1ar en sus declaraciones. \u00c9l solo quiso precisar algunas cosas.<br \/>\n\u2013Por qu\u00e9 cree que hasta ahora solo han respondido al llamado de Humala las fuerzas de izquierda?<br \/>\n\u2013No, no es as\u00ed. Hay m\u00faltiples movimientos regionales de diferente orden, movimientos vecinales, provinciales, que se ha constituido y quieren unirse al frente amplio. Ahora bien, las fuerzas de izquierda tampoco tienen por qu\u00e9 ser discriminadas.<br \/>\n\u2013Quien las ha discriminado hace unos d\u00edas fue el ex candidato a vicepresidente Carlos Torres Caro&#8230;.<br \/>\n\u2013Desconozco que el se\u00f1or Torres Caro haya regresado a sus primeras declaraciones, pero lo que s\u00ed es muy curioso es la arremetida que hay contra todo lo que sea izquierda en el Per\u00fa. Eso s\u00ed llamar\u00eda a la preocupaci\u00f3n, porque en un pa\u00eds democr\u00e1tico se aceptan todas las tendencias.<br \/>\n<strong><a href=\"http:\/\/www.elcomercioperu.com.pe\/EdicionImpresa\/Html\/2006-06-10\/impPolitica0520459.html\">UPP se\u00f1ala que todav\u00eda no se dan las condiciones para conversar con l\u00edder aprista<\/a><br \/>\nEl Comercio, 10 de junio del 2006<\/strong><br \/>\nPiden el &#8220;cese de guerra sucia y de las campa\u00f1as psicosociales&#8221; en contra de Ollanta Humala.<br \/>\nOllanta Humala no contest\u00f3 a la invitaci\u00f3n formulada por el virtual presidente Alan Garc\u00eda P\u00e9rez. Fue el secretario general de Uni\u00f3n por el Per\u00fa (UPP), Jos\u00e9 Vega Antonio, quien en conferencia de prensa respondi\u00f3 en nombre de su l\u00edder y condicion\u00f3 la cita a que &#8220;primero tendr\u00eda que cesar la campa\u00f1a psicosocial contra Ollanta Humala&#8221;.<br \/>\nSeg\u00fan el secretario general de UPP, la guerra sucia se muestra en las declaraciones del virtual primer vicepresidente, Luis Giampietri, quien se\u00f1al\u00f3 ayer que Ollanta Humala intentaba desestabilizar al pa\u00eds para impedir la correcta transici\u00f3n democr\u00e1tica el pr\u00f3ximo 28 de julio.<br \/>\nEsta actitud, seg\u00fan Vega Antonio, impide que se generen &#8220;las condiciones para que Ollanta Humala converse con Alan Garc\u00eda&#8221;.<br \/>\nDurante la conferencia de prensa, el ex candidato a la primera vicepresidencia, Gonzalo Garc\u00eda N\u00fa\u00f1ez, neg\u00f3 enf\u00e1ticamente que Ollanta Humala se encuentre preparando un alzamiento militar para afectar la democracia el pr\u00f3ximo 28 de julio.<br \/>\nPor otro lado, el vocero de UPP, Carlos Tapia, exhort\u00f3 al virtual presidente a que, junto con el ex candidato aprista al Congreso, Benedicto Jim\u00e9nez, aclare si los servicios de inteligencia durante el nuevo gobierno realizar\u00e1n un seguimiento a Humala Tasso.<br \/>\n&#8220;Si el virtual jefe de Estado hace todas esas aclaraciones p\u00fablicamente, las condiciones mejorar\u00edan para generar un di\u00e1logo&#8221;, se\u00f1al\u00f3 Carlos Tapia.<br \/>\nGonzalo Garc\u00eda N\u00fa\u00f1ez se\u00f1al\u00f3 que desde UPP no se le iba a dar tregua al Partido Aprista porque &#8220;eso ser\u00eda detener nuestra lucha contra la corrupci\u00f3n y la pobreza&#8221;.<br \/>\n&#8220;Fiscalizaremos funciones del Apra&#8221;<br \/>\nCarlos Tapia, vocero de UPP, se\u00f1al\u00f3 que su partido se constituye en una fuerza de oposici\u00f3n con la leg\u00edtima autoridad que le da el 47 % del voto de la poblaci\u00f3n en todo el pa\u00eds y las 45 curules alcanzadas en el Congreso de la Rep\u00fablica.<br \/>\nAl mismo tiempo, Jos\u00e9 Vega, secretario general de UPP, se\u00f1al\u00f3 que su partido se dedicar\u00e1 a fiscalizar las funciones del Partido Aprista. Asimismo, exigir\u00e1n desde el Parlamento el cumplimiento de las promesas, en especial las destinadas a erradicar la pobreza.<br \/>\n<strong><a href=\"http:\/\/www.peru21.com\/comunidad\/columnistas\/html\/DirectorIndex.html\">Momentos imborrables<\/a><br \/>\nLa cita pendiente entre Alan Garc\u00eda y Ollanta Humala<br \/>\nPer\u00fa 21, 10 de junio del 2006. Por Augusto \u00c1lvarez Rodrich. La Opini\u00f3n del Director.<\/strong><br \/>\nJunto con la declaraci\u00f3n oficial del resultado, lo \u00fanico que faltar\u00eda para terminar el proceso electoral es una fotograf\u00eda de Alan Garc\u00eda con Ollanta Humala.<br \/>\n\u00bfCu\u00e1n importante es que ambos se re\u00fanan, aunque sea un ratito, para conversar sobre lo que les venga en gana, darse un apret\u00f3n de manos y ofrecer la tradicional fotograf\u00eda?<br \/>\nEn rigor, esta podr\u00eda obviarse sin afectar el proceso. No obstante, el rechazo de Humala a esta cita con el presidente electo produce una especulaci\u00f3n innecesaria sobre la verdadera intenci\u00f3n que hay detr\u00e1s de su prop\u00f3sito de romper esta tradici\u00f3n de la pol\u00edtica peruana.<br \/>\nUna posibilidad es que Humala haya quedado realmente ofendido por los agravios que Garc\u00eda le lanz\u00f3 durante la campa\u00f1a -como aquel de &#8220;asesino de polic\u00edas&#8221;-, pero tambi\u00e9n es cierto que el candidato de &#8216;la olla&#8217; golpe\u00f3 con dureza similar al postulante de &#8216;la estrella&#8217;.<br \/>\nSin embargo, a pesar de la manifiesta falta de empat\u00eda y de la elevada desconfianza rec\u00edproca entre los dos candidatos de la segunda vuelta, es evidente la conveniencia de que el pr\u00f3ximo presidente de la Rep\u00fablica y el l\u00edder de la oposici\u00f3n tengan ahora alg\u00fan tipo de puente incluso para afirmar sus diferencias.<br \/>\nLa se\u00f1al que Humala proyecta con esta resistencia es negativa pues alienta las versiones de que no est\u00e1 dispuesto a seguir &#8216;las reglas del juego&#8217;, aun cuando esto fuera falso.<br \/>\nEs evidente que se ha deteriorado sustantivamente la posibilidad de un acuerdo entre sus respectivos partidos. Adem\u00e1s, pullazos entre ambos habr\u00e1 muchos y de diverso calibre durante el lustro siguiente, algunos de los cuales ya se perciben en estos d\u00edas. Por ejemplo, el inaceptable anuncio de Benedicto Jim\u00e9nez -voceado para ministro del Interior- de que el Servicio de Inteligencia deber\u00eda vigilar a quien el propio Garc\u00eda ha reconocido como &#8216;l\u00edder de la oposici\u00f3n&#8217;.<br \/>\nPero incluso para hacer notar estos errores y para remarcar sus leg\u00edtimas posiciones pol\u00edticas, se necesita dar las se\u00f1ales de que, al margen de las obvias diferencias, se podr\u00e1 llevar la &#8216;fiesta en paz&#8217;. Y esa fotito que falta ayudar\u00eda un poco.<br \/>\n<strong><a href=\"http:\/\/www.laprimera.com.pe\/noticia.php?IDnoticia=24678\">Ollanta no acepta invitaci\u00f3n de Alan <\/a><br \/>\nVoceros nacionalistas dicen que no est\u00e1n dadas las condiciones si no cesan ataques contra su l\u00edder.<br \/>\nLa Primera, 10 de junio del 2006<\/strong><br \/>\nUn no rotundo es la respuesta que le han dado los voceros nacionalistas al virtual presidente, Alan Garc\u00eda, luego que \u00e9ste hiciera p\u00fablicas sus intenciones de reunirse en privado con Ollanta Humala para abordar temas de inter\u00e9s nacional.<br \/>\nJos\u00e9 Vega Antonio, el secretario general de UPP, advirti\u00f3 que mientras no cesen todos los ataques, insultos y psicosociales apristas contra el l\u00edder nacionalista no est\u00e1n dadas las condiciones para que puedan sentarse a la mesa Garc\u00eda P\u00e9rez y Humala Tasso.<br \/>\nCuestion\u00f3 que el pr\u00f3ximo presidente aprista quiera concertar una cita con Humala Tasso pese a que \u00e9ste preparar\u00eda un supuesto golpe militar cuando asuma el poder, como lo denunci\u00f3 el virtual vicepresidente de la Rep\u00fablica, Luis Giampietri.<br \/>\nTambi\u00e9n critic\u00f3 que el ex candidato al Congreso por el APRA coronel (r) Benedicto Jim\u00e9nez haya indicado que cuando lleguen al poder ordenar\u00edan a los servicios de inteligencia realizar seguimientos selectivos a Humala Tasso y otros l\u00edderes pol\u00edticos para conocer sus movimientos.<br \/>\nQUE ALAN HABLE<br \/>\nCon sarcasmo, el vocero de UPP, Carlos Tapia, aconsej\u00f3 a Garc\u00eda P\u00e9rez sentarse primero a conversar con Giampietri y Jim\u00e9nez para saber lo que est\u00e1n diciendo del nacionalista, antes de pedir una cita con \u00e9ste.<br \/>\nTapia asegur\u00f3 que si el virtual presidente sale a decir p\u00fablicamente si cree en la tesis golpista y si iniciar\u00e1n una \u201cpersecuci\u00f3n pol\u00edtica\u201d contra los l\u00edderes de la oposici\u00f3n de la mano con Inteligencia, \u201csospecho que habr\u00eda mucho mejores condiciones para tener un di\u00e1logo m\u00e1s directo\u201d.<br \/>\nAyer, Garc\u00eda P\u00e9rez se\u00f1al\u00f3 que no daba cr\u00e9dito al presunto golpe militar que pretender\u00eda encabezar Humala Tasso.<br \/>\nEn todo caso, hay que anotar que el ex candidato a la vicepresidencia de la Rep\u00fablica por UPP, Gonzalo Garc\u00eda, desestim\u00f3 que las declaraciones de Giampietri y Jim\u00e9nez se hayan visto azuzadas tras la negativa de Humala Tasso de darle una tregua al pr\u00f3ximo gobierno aprista.<br \/>\nRatific\u00f3 en que no le dar\u00e1n ning\u00fan periodo de gracia al virtual presidente y que, por el contrario, asumir\u00e1n una \u201cfirme posici\u00f3n de vigilancia y fiscalizaci\u00f3n\u201d.<br \/>\nEs m\u00e1s, afirm\u00f3 que las bases apristas deben revolver la tumba de V\u00edctor Ra\u00fal Haya de la Torre, porque la bancada aprista se negar\u00e1 a volver a la Constituci\u00f3n de 1979, pese a que el fundador del partido presidi\u00f3 la Asamblea Constituyente de ese entonces.<br \/>\nReducci\u00f3n de sueldos<br \/>\nLa flamante bancada UPP-PNP suscribir\u00e1 el proyecto legislativo aprista para reducir dr\u00e1sticamente los sueldos a los congresistas y funcionarios p\u00fablicos, lo cual figuraba en el plan de gobierno nacionalista, adelant\u00f3 Gonzalo Garc\u00eda.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1305,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7951],"tags":[],"class_list":["post-1438","post","type-post","status-publish","format-standard","hentry","category-political-parties"],"_links":{"self":[{"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/posts\/1438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/users\/1305"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/comments?post=1438"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/posts\/1438\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/media?parent=1438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/categories?post=1438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/tags?post=1438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}