{"id":1456,"date":"2006-06-15T09:43:58","date_gmt":"2006-06-15T17:43:58","guid":{"rendered":"https:\/\/blogs.ubc.ca\/peru\/2006\/06\/15\/encuesta-post-electoral-de-la-u-de-lima\/"},"modified":"2006-06-15T09:43:58","modified_gmt":"2006-06-15T17:43:58","slug":"encuesta-post-electoral-de-la-u-de-lima","status":"publish","type":"post","link":"https:\/\/blogs.ubc.ca\/peru\/2006\/06\/15\/encuesta-post-electoral-de-la-u-de-lima\/","title":{"rendered":"Encuesta Post Electoral de la U. de Lima"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" alt=\"post\" src=\"https:\/\/blogs.ubc.ca\/peru\/files\/2010\/04\/archives\/post\" width=\"681\" height=\"715\" \/><br \/>\nSource: <a href=\"http:\/\/www.larepublica.com.pe\/index.php?option=com_content&amp;task=view&amp;id=113638&amp;Itemid=483&amp;fecha_edicion=2006-06-15\">La Rep\u00fablica<\/a>, 15 de junio del 2006<br \/>\nFicha t\u00e9cnica<br \/>\nUNIVERSO: Hombres y mujeres residentes en Lima Metropolitana y el Callao, entre 18 y 70 a\u00f1os de edad, de todos los niveles socioecon\u00f3micos. MUESTRA: 500 personas. SUPERVISI\u00d3N: 30% de la muestra mediante la t\u00e9cnica de la visita. APLICACI\u00d3N DEL CUESTIONARIO: S\u00e1bado 10 y domingo 11 de junio de 2006. REPRESENTATIVIDAD: 94,69%. FINANCIAMIENTO: Universidad de Lima.<\/p>\n<p><!--more--><br \/>\n<em><strong><a href=\"http:\/\/www.larepublica.com.pe\/index.php?option=com_content&amp;task=view&amp;id=113638&amp;Itemid=483&amp;fecha_edicion=2006-06-15\">47% cree que el Per\u00fa estar\u00e1 mejor tras la gesti\u00f3n de Garc\u00eda<\/a><br \/>\nLa Rep\u00fablica, 15 de junio del 2006. Por Flor Huilca.<\/strong><br \/>\nENCUESTA DE U. DE LIMA<br \/>\n\u2022 El 20.3% se\u00f1ala que Alan gan\u00f3 porque &#8220;no hab\u00eda otra opci\u00f3n&#8221;<br \/>\n\u2022 El 19.2% considera que Ollanta Humala perdi\u00f3 porque &#8220;es autoritario&#8221;.<br \/>\nLos peruanos se muestran optimistas con el pr\u00f3ximo gobierno. Una encuesta de la Universidad de Lima post elecciones revela que el 47.7% de los encuestados conf\u00eda en que con la gesti\u00f3n de Alan Garc\u00eda el pa\u00eds ser\u00e1 mejor, el 20% considera que estaremos igual, mientras que el 13% cree que estaremos peor.<br \/>\nEl grueso de los que consideran que estaremos mejor dentro de cinco a\u00f1os se ubica en los sectores de clase media (B: 58.8% y C: 57.3%). En el sector A hay esa sensaci\u00f3n en un 45%, en tanto que entre los m\u00e1s pobres (E) es m\u00e1s baja esa confianza: 28.8%.<br \/>\nEl 61.7% de los entrevistados se mostr\u00f3 tambi\u00e9n de acuerdo con la elecci\u00f3n del candidato aprista como presidente. El 80% est\u00e1 en el sector A y el 50% en el sector E. Los que est\u00e1n en desacuerdo con la elecci\u00f3n representan el 32%. La mayor\u00eda de quienes piensan as\u00ed pertenecen a los sectores populares (45%), al sector A pertenece el 15%. Hay que recordar que fueron los sectores m\u00e1s pobres los que votaron a favor de Ollanta Humala en los dos procesos electorales.<br \/>\nSi bien hubo denuncias de guerra sucia en ambos procesos electorales, los encuestados creen que la campa\u00f1a electoral de la segunda vuelta fue m\u00e1s limpia (53.4%) que en la primera vuelta (47.7%). La percepci\u00f3n de quienes creen que la campa\u00f1a fue sucia tambi\u00e9n es diferente. El 40.1% cree que tuvo esas caracter\u00edsticas la elecci\u00f3n del 9 de abril, y el 30% la elecci\u00f3n del 4 de junio.<br \/>\nA los encuestados se les pidi\u00f3, adem\u00e1s, dar de modo espont\u00e1neo las razones por las cuales creen que gan\u00f3 el candidato del Apra y perdi\u00f3 el candidato de UPP.<br \/>\nLa primera raz\u00f3n que explica el triunfo de Alan Garc\u00eda, seg\u00fan los encuestados, es &#8220;porque no hab\u00eda otro candidato&#8221; 20.3%. En el sector A se encuentra el 52.5% de quienes lo creen as\u00ed y en el sector E el 3.8%. En el caso de Ollanta la primera raz\u00f3n es &#8220;porque es autoritario&#8221; con 19.2%. La composici\u00f3n socioecon\u00f3mica de esa respuesta es 42.5% en el A y 11.3% en el E.<br \/>\nEn tanto, el 11% de los encuestados revela haber decidido su voto el mismo 4 de junio. La mayor\u00eda (62.7%) lo decidi\u00f3 despu\u00e9s de la primera vuelta.<br \/>\nClaves<br \/>\nLA MAYOR\u00cdA VOT\u00d3. El 96.5% revel\u00f3 que acudi\u00f3 a votar en segunda vuelta, y el 96.2% lo hizo en la primera vuelta.<br \/>\nES UN DEBER. Quienes fueron a votar en la segunda vuelta dicen que su principal raz\u00f3n fue porque consideran que es un deber ciudadano (52%), el 20.25 porque el pa\u00eds necesita un cambio.<br \/>\nNOTABLE. Los encuestados consideran como muy buena la labor de ONPE (63.4%) y el JNE (61.1%) en la segunda vuelta.<br \/>\n<a href=\"http:\/\/www.laprimera.com.pe\/noticia.php?IDnoticia=24958\">En Lima el 61% aprueba elecci\u00f3n de Alan Garc\u00eda <\/a><br \/>\nLime\u00f1os consideran que el pa\u00eds ser\u00e1 mejor con gesti\u00f3n de Garc\u00eda, seg\u00fan encuesta de U. de Lima.<br \/>\nLa Primera, 15 de junio del 2006<br \/>\nSeg\u00fan el \u00faltimo bar\u00f3metro postelectoral publicado por la Universidad de Lima, el 61,7% dijo estar de acuerdo con la elecci\u00f3n de Alan Garc\u00eda como presidente de la Rep\u00fablica, el 32% se manifest\u00f3 en desacuerdo, el 5,2% no sab\u00eda y el 1,1% no contest\u00f3.<br \/>\nEntre las razones por las cuales los lime\u00f1os consideran que gan\u00f3 Garc\u00eda figuran: porque no hab\u00eda otra opci\u00f3n (20,3%), porque est\u00e1 bien preparado y tiene experiencia (14,8%) y porque recibi\u00f3 el apoyo de otros partidos (11,6%).<br \/>\nAsimismo, el 9,6% anot\u00f3 que Garc\u00eda gan\u00f3 porque tuvo buenas propuestas, el 7,8% porque representa la democracia, y el 5% porque considera que es un gran orador y tiene carisma.<br \/>\nA su vez, entre las razones por las que perdi\u00f3 Ollanta Humala figuran: porque es un autoritario (19,2%), por las intervenciones de Hugo Ch\u00e1vez (17,7%), porque es muy radical (13,5%), y porque su propuesta nacionalista no convenci\u00f3 (8%).<br \/>\nDe igual forma, el 5,7% consider\u00f3 que Humala perdi\u00f3 la segunda vuelta porque no hizo una buena campa\u00f1a, y el 5,6% porque no ten\u00eda buenas propuestas.<br \/>\nMEJORAREMOS<br \/>\nDe otra parte, el 47,7% de lime\u00f1os considera que con la gesti\u00f3n presidencial de Alan Garc\u00eda el Per\u00fa ser\u00e1 mejor dentro de cinco a\u00f1os.<br \/>\nDe acuerdo al sondeo, realizado entre el 10 y 11 de junio en Lima y el Callao, el 20% de los consultados indica que el pa\u00eds ser\u00e1 igual tras el gobierno de Garc\u00eda y el 13% mencion\u00f3 que ser\u00e1 peor. S\u00f3lo el 19,4% de los encuestados no respondi\u00f3 a la pregunta.<br \/>\nEn otro aspecto, el 56,1% de los encuestados consider\u00f3 que la reciente campa\u00f1a electoral fue limpia y muy limpia, mientras que el 38,3% dijo que fue sucia y muy sucia.<br \/>\nRespecto del papel del Jurado Nacional de Elecciones (JNE), el 60,1% lo calific\u00f3 de bueno y muy bueno, el 30,5% de regular y el 6,5% de malo y muy malo.<br \/>\nEn el caso de la Oficina Nacional de Procesos Electorales (ONPE), el 63,4% se\u00f1al\u00f3 que su desempe\u00f1o fue bueno y muy bueno, el 28,5% de regular y el 6,1% de malo y muy malo.<br \/>\nFicha t\u00e9cnica<br \/>\nUNIVERSO: Hombres y mujeres residentes en Lima Metropolitana y el Callao, entre 18 y 70 a\u00f1os de edad, de todos los niveles socioecon\u00f3micos. MUESTRA: 500 personas. SUPERVISI\u00d3N: 30% de la muestra mediante la t\u00e9cnica de la visita. APLICACI\u00d3N DEL CUESTIONARIO: S\u00e1bado 10 y domingo 11 de junio de 2006. REPRESENTATIVIDAD: 94,69%. FINANCIAMIENTO: Universidad de Lima.<br \/>\n<strong><a href=\"http:\/\/www.correoperu.com.pe\/paginas_nota.php?nota_id=28225&amp;seccion_nota=1\">Un 47.7% de lime\u00f1os cree que con Alan estaremos mejor dentro de cinco a\u00f1os<\/a><br \/>\nSeg\u00fan encuesta de la Universidad de Lima, injerencia de Hugo Ch\u00e1vez figura entre las razones de la derrota de Humala<br \/>\nDiario Correo, 14 de junio del 2006<\/strong><br \/>\nAparentemente la impresi\u00f3n de que un gobierno aprista ser\u00e1 nefasto para el pa\u00eds se est\u00e1 disipando, al menos en Lima y Callao. Y es que un 47.7% considera que con la gesti\u00f3n de Alan Garc\u00eda el Per\u00fa estar\u00e1 mejor dentro de cinco a\u00f1os, seg\u00fan el bar\u00f3metro post electoral del Grupo de Opini\u00f3n P\u00fablica de la Universidad de Lima.<br \/>\nSeg\u00fan el sondeo, un 20.0% piensa que la situaci\u00f3n del pa\u00eds ser\u00e1 igual y un 13.0% que ser\u00e1 peor. Otro 19.4% prefiri\u00f3 no contestar.<br \/>\nUn 61.7% est\u00e1 de acuerdo con la elecci\u00f3n del l\u00edder aprista, mientras que un 32.0% piensa lo contrario. Entre las razones por las que Garc\u00eda gan\u00f3 la elecci\u00f3n podemos se\u00f1alar que un 20.3% aduce que no hab\u00eda otra opci\u00f3n, 14.8% expres\u00f3 que est\u00e1 bien preparado y tiene experiencia, y 11.6% dice que recibi\u00f3 el apoyo de otros partidos.<br \/>\nOtro 6.5% piensa que triunf\u00f3 porque hab\u00eda que darle una nueva oportunidad, 3.1% porque hubo fraude, 2.4% por temor a Ollanta Humala.<br \/>\nEn el caso de Humala, un 19.2% piensa que perdi\u00f3 porque es autoritario, 17.7% por la intervenci\u00f3n de Hugo Ch\u00e1vez y un 13.5% porque es muy radical. <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Source: La Rep\u00fablica, 15 de junio del 2006 Ficha t\u00e9cnica UNIVERSO: Hombres y mujeres residentes en Lima Metropolitana y el Callao, entre 18 y 70 a\u00f1os de edad, de todos los niveles socioecon\u00f3micos. MUESTRA: 500 personas. SUPERVISI\u00d3N: 30% de la muestra mediante la t\u00e9cnica de la visita. APLICACI\u00d3N DEL CUESTIONARIO: S\u00e1bado 10 y domingo 11 [&hellip;]<\/p>\n","protected":false},"author":1305,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7949],"tags":[],"class_list":["post-1456","post","type-post","status-publish","format-standard","hentry","category-polls-results"],"_links":{"self":[{"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/posts\/1456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/users\/1305"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/comments?post=1456"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/posts\/1456\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/media?parent=1456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/categories?post=1456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ubc.ca\/peru\/wp-json\/wp\/v2\/tags?post=1456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}