{"id":51,"date":"2014-10-21T10:19:17","date_gmt":"2014-10-21T17:19:17","guid":{"rendered":"https:\/\/blogs.ubc.ca\/srasmussen\/?p=51"},"modified":"2014-10-21T10:19:17","modified_gmt":"2014-10-21T17:19:17","slug":"oct-21","status":"publish","type":"post","link":"https:\/\/blogs.ubc.ca\/srasmussen\/2014\/10\/21\/oct-21\/","title":{"rendered":"Oct 21"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1124760],"tags":[],"class_list":["post-51","post","type-post","status-publish","format-standard","hentry","category-ib-posts"],"_links":{"self":[{"href":"https:\/\/blogs.ubc.ca\/srasmussen\/wp-json\/wp\/v2\/posts\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ubc.ca\/srasmussen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ubc.ca\/srasmussen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ubc.ca\/srasmussen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ubc.ca\/srasmussen\/wp-json\/wp\/v2\/comments?post=51"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ubc.ca\/srasmussen\/wp-json\/wp\/v2\/posts\/51\/revisions"}],"predecessor-version":[{"id":52,"href":"https:\/\/blogs.ubc.ca\/srasmussen\/wp-json\/wp\/v2\/posts\/51\/revisions\/52"}],"wp:attachment":[{"href":"https:\/\/blogs.ubc.ca\/srasmussen\/wp-json\/wp\/v2\/media?parent=51"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ubc.ca\/srasmussen\/wp-json\/wp\/v2\/categories?post=51"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ubc.ca\/srasmussen\/wp-json\/wp\/v2\/tags?post=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}