{"id":9,"date":"2018-01-17T21:37:34","date_gmt":"2018-01-18T04:37:34","guid":{"rendered":"https:\/\/blogs.ubc.ca\/streitzspan\/?p=9"},"modified":"2018-01-18T11:38:03","modified_gmt":"2018-01-18T18:38:03","slug":"reflexion-2","status":"publish","type":"post","link":"https:\/\/blogs.ubc.ca\/streitzspan\/2018\/01\/17\/reflexion-2\/","title":{"rendered":"Reflexi\u00f3n 2"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Comentario sobre El cisne<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Creo que la poema habla sobre una \u00e9poca nueva de los humanos. El cisne es una s\u00edmbolo para la \u00e9poca nueva, y las personas mitol\u00f3gicos son s\u00edmbolos para el \u00e9poca viejo. Se use las personas mitol\u00f3gicos porque representan la literatura tradicional. Son parte de la literatura que los estudiantes secundarios estudian. El autor quiere crear una contrasto entre la literatura tradicional, y la literatura moderna. El cisne es una s\u00edmbolo de la literatura moderna. Tambi\u00e9n, el autor escribe: \u201calas la nueva Poes\u00eda concibe en una gloria\u201d. A m\u00ed, este implique que la Poes\u00eda es la forma de la literatura moderna. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le\u00ed el parte del texto \u201cEl autor y su contexto\u201d despu\u00e9s que escrib\u00ed esta reflexi\u00f3n, y me d\u00ed cuenta porque la poes\u00eda tiene contrasta la literatura tradicional y moderna. Quizas es porque Dar\u00edo ten\u00eda influencia en el movimiento de modernismo. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Comentario sobre \u201cCanci\u00f3n de oto\u00f1o en primaveras\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mi primera impresi\u00f3n de este poema es que es muy bella. La lengua es muy fluido, y parece la m\u00e1s po\u00e9tica de todos las poes\u00edas que hemos le\u00eddo. No entiendo el mensaje del poema. Quizas habla sobre el amor. Pero estoy confundido porque habla tanto sobre la \u201cjuventud\u201d. Me gusta la repetici\u00f3n de la poema. Tambien me gusta la ultima linea, pero no se de que habla.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Porque el autor usa el soneto?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comentario sobre El cisne &nbsp; Creo que la poema habla sobre una \u00e9poca nueva de los humanos. El cisne es una s\u00edmbolo para la \u00e9poca nueva, y las personas mitol\u00f3gicos son s\u00edmbolos para el \u00e9poca viejo. Se use las personas mitol\u00f3gicos porque representan la literatura tradicional. Son parte de la literatura que los estudiantes secundarios [&hellip;]<\/p>\n","protected":false},"author":34775,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.ubc.ca\/streitzspan\/wp-json\/wp\/v2\/posts\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ubc.ca\/streitzspan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ubc.ca\/streitzspan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ubc.ca\/streitzspan\/wp-json\/wp\/v2\/users\/34775"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ubc.ca\/streitzspan\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":2,"href":"https:\/\/blogs.ubc.ca\/streitzspan\/wp-json\/wp\/v2\/posts\/9\/revisions"}],"predecessor-version":[{"id":11,"href":"https:\/\/blogs.ubc.ca\/streitzspan\/wp-json\/wp\/v2\/posts\/9\/revisions\/11"}],"wp:attachment":[{"href":"https:\/\/blogs.ubc.ca\/streitzspan\/wp-json\/wp\/v2\/media?parent=9"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ubc.ca\/streitzspan\/wp-json\/wp\/v2\/categories?post=9"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ubc.ca\/streitzspan\/wp-json\/wp\/v2\/tags?post=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}