{"id":979532,"count":1,"description":"","link":"https:\/\/blogs.ubc.ca\/trolls\/tag\/startled\/","name":"Startled","slug":"startled","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.ubc.ca\/trolls\/wp-json\/wp\/v2\/tags\/979532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ubc.ca\/trolls\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.ubc.ca\/trolls\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.ubc.ca\/trolls\/wp-json\/wp\/v2\/posts?tags=979532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}